{"id":11602,"date":"2018-10-15T16:21:28","date_gmt":"2018-10-15T14:21:28","guid":{"rendered":"https:\/\/www.diamantrad.com\/blog\/?p=4494"},"modified":"2025-03-24T14:40:08","modified_gmt":"2025-03-24T13:40:08","slug":"fahrrad-fahrbereit-machen","status":"publish","type":"post","link":"https:\/\/www.diamantrad.com\/de-DE\/blog\/fahrrad-fahrbereit-machen\/","title":{"rendered":"Fahrrad fahrbereit machen &#8211; Tipps f\u00fcr die (erste) Inbetriebnahme"},"content":{"rendered":"\n<p class=\"db-intro\">Vor der ersten&nbsp;Ausfahrt mit einem neuen oder geliehenen Fahrrad sollten sich Radfahrer mit der Bedienung vertraut machen, um Fehlbedienungen zu vermeiden. Indem du dabei das Rad gr\u00fcndlich durchcheckst, kannst du gleich beide To-Dos in einem Rutsch erledigen.<\/p>\n\n\n\n<p>Worauf Radfahrer vor der ersten Fahrt achten sollten und welche Fahrradteile beim Fahrrad-Check wichtig sind, erf\u00e4hrst du hier im Diamant-Blog. F\u00fcr die Ausfahrten danach findest du weiter unten eine Checkliste mit den wichtigsten Fahrradteilen, die du vor jeder Fahrt im Blick haben solltest.<\/p>\n\n\n\n<p class=\"mb-5\"><strong>Achtung:<\/strong> Die folgenden Tipps &amp; Hinweise beinhalten Funktionsbeschreibungen, die f\u00fcr unterschiedliche&nbsp;Modelle und Ausstattungsvarianten g\u00fcltig sind. Nicht alle beschriebenen&nbsp;Komponenten sind an deinem Fahrrad verbaut worden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die richtige Rahmengr\u00f6\u00dfe f\u00fcr Dein Rad<\/h2>\n\n\n\n<p>Vergewissere dich, dass das Fahrrad die&nbsp;richtige Gr\u00f6\u00dfe hat. Ob das Rad die richtige Ma\u00dfe f\u00fcr deine K\u00f6rpergr\u00f6\u00dfe hat, kannst du pr\u00fcfen, indem du den Abstand zwischen Oberrohr und Schritt ausmisst,&nbsp;wenn du \u00fcber dem Fahrrad stehst (Abb.&nbsp;1). Das Fahrrad mit den richtigen&nbsp;Ma\u00dfen f\u00fcr deine K\u00f6rpergr\u00f6\u00dfe hat einen Mindestabstand von 25&nbsp;mm.&nbsp;Bei einem Mountainbike empfehlen wir einen&nbsp;Abstand zwischen 50 und 75&nbsp;mm. <a href=\"https:\/\/www.diamantrad.com\/bikes\/damenraeder\/\">Damen-Fahrr\u00e4der<\/a> oder Tiefeinsteiger weisen einen gr\u00f6\u00dferen Abstand vor bzw. besitzen kein Oberrohr.<\/p>\n\n\n\n<p><strong>Hinweis:<\/strong> Beachte, dass f\u00fcr den Zusammenbau und die ersten&nbsp;Einstellungen deines Fahrrades spezielle&nbsp;Werkzeuge und Kenntnisse erforderlich sind. Lasse diese Arbeiten daher gegebenenfalls von deinem Fahrrad-Fachh\u00e4ndler durchf\u00fchren.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone mb-5\"><img decoding=\"async\" sizes=\"(max-width: 2000px) 100vw, 2000px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/08\/fahrrad-tipps-abstand-radfahrer-oberrohr-diamant-blog.jpg\" alt=\"Abstand vom Schritt zum Fahrrad-Oberrohr. Diamant-Blog\" class=\"wp-image-4913\"\/><figcaption class=\"wp-element-caption\">Abb. 1 &#8211; Die richtige Rahmengr\u00f6\u00dfe l\u00e4sst sich am Abstand vom Schritt zum&nbsp;Oberrohr&nbsp;im Stand (A) erkennen.&nbsp;&#8211; Diamant-Blog<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Fahreigenschaften testen<\/h2>\n\n\n\n<p>Ob Damen- oder <a href=\"https:\/\/www.diamantrad.com\/bikes\/herrenraeder\/\">Herrenr\u00e4der<\/a>, E-Bikes oder ohne Motor &#8211; jedes Fahrrad hat bestimmte Fahreigenschaften. Bei falscher Fahrtechnik k\u00f6nnen sie dazu f\u00fchren, dass du das Rad weniger unter&nbsp;Kontrolle hast. Bevor du schnell oder unter&nbsp;schwierigen Bedingungen f\u00e4hrst, musst du dich mit der Bedienung und Funktionsweise&nbsp;der Mechanismen des Fahrrades vertraut&nbsp;machen.<\/p>\n\n\n\n<p>Achte dabei insbesondere auf Bremsen und&nbsp;Lenkkomponenten. \u201eAerolenker\u201c k\u00f6nnen&nbsp;beispielsweise das Lenken und das Bremsen erschweren. <a title=\"https:\/\/www.diamantrad.com\/bikes\/ebikes\/\" href=\"https:\/\/www.diamantrad.com\/bikes\/ebikes\/\" target=\"\" rel=\"noopener noreferrer\">E-Bikes<\/a> weisen durch den eingebauten Motorantrieb ebenfalls andere Fahreigenschaften vor.<\/p>\n\n\n\n<p class=\"mb-5\">\u00dcbe das Fahren mit deinem Rad bei geringen&nbsp;Geschwindigkeiten auf einem ebenen,&nbsp;leeren Parkplatz &#8211; auch wenn du etwas an deinem Fahrrad ge\u00e4ndert hast. Teste die Schaltung und wie sich das Rad beim Fahren verh\u00e4lt. \u00dcbe bei einem E-Bike zun\u00e4chst in der kleinsten Unterst\u00fctzungseinheit. Wenn Dein Fahrrad nicht die erforderlichen&nbsp;Fahreigenschaften aufweist oder andere Dinge dazu f\u00fchren, dass du nicht <a title=\"Sicher mit dem Fahrrad unterwegs \u2013 Regeln &amp; Hinweise\" href=\"https:\/\/www.diamantrad.com\/blog\/regeln-hinweise-sicheres-fahrradfahren\/\" target=\"\" rel=\"noopener noreferrer\">sicher mit dem Fahrrad unterwegs<\/a> sein kannst, wende dich an deinen Fahrrad-Fachh\u00e4ndler.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Leistung der Fahrradbremsen pr\u00fcfen<\/h2>\n\n\n\n<p>Die Bremsleistung von Fahrradbremsen ist von der Nutzungsart des Fahrrades&nbsp;abh\u00e4ngig. Es kann passieren, dass du das Bremssystem&nbsp;nicht ordnungsgem\u00e4\u00df verwendest oder zu viel Kraft mit der Vorderradbremse&nbsp;aus\u00fcbst. In diesem Fall k\u00f6nnten die Bremsen deine Kontrolle&nbsp;vermindern. Um einen Sturz zu vermeiden, \u00fcbe&nbsp;den Einsatz der Fahrradbremsen. Wiederhole die Gew\u00f6hnungsphase mit Bremstest beim E-Bike f\u00fcr alle Fahrstufen.<\/p>\n\n\n\n<p class=\"mb-5\"><strong>Hinweis:<\/strong> Wenn Dein Fahrrad mehr oder&nbsp;weniger Bremskraft ben\u00f6tigt, lasse dich von deinem Fachh\u00e4ndler zu den&nbsp;Bremseinstellungen und alternativen&nbsp;Bremsoptionen beraten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcberschneidungen der Pedalhaken vermeiden<\/h2>\n\n\n\n<p>Einige moderne Hochleistungsfahrr\u00e4der, insbesondere in kleineren Gr\u00f6\u00dfen, haben einen&nbsp;k\u00fcrzeren Radstand, sodass das Vorderrad n\u00e4her an den Pedalen liegt. Bei niedrigen Geschwindigkeiten kann es&nbsp;vorkommen, dass die Fu\u00dfspitzen oder&nbsp;der Pedalhaken das Vorderrad oder das&nbsp;Schutzblech bei Lenkbewegungen&nbsp;ber\u00fchren (Abb.&nbsp;2). Wegen&nbsp;der \u00dcberschneidung hast du dann m\u00f6glicherweise&nbsp;nur noch eine eingeschr\u00e4nkte Kontrolle \u00fcber&nbsp;das Fahrrad. Bei normalen&nbsp;Geschwindigkeiten kommt es in der Regel zu keiner Ber\u00fchrung, da der Fahrradlenker nicht&nbsp;so weit eingeschlagen wird. Trete daher bei niedrigen&nbsp;Geschwindigkeiten und eingeschlagenem&nbsp;Lenker besser nicht in die Pedale.<\/p>\n\n\n\n<p><strong>Tipp:<\/strong> Die Fu\u00dffreiheit auf dem Rad ist abh\u00e4ngig von der Gr\u00f6\u00dfe deiner F\u00fc\u00dfe, der L\u00e4nge der Kurbelarme, der&nbsp;Gr\u00f6\u00dfe der Reifen und den Pedalen. Somit l\u00e4sst sich die Fu\u00dffreiheit \u00e4ndern, wenn du die genannten&nbsp;Komponenten auswechselst.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone mb-5\"><img data-dominant-color=\"e17f7e\" data-has-transparency=\"false\" style=\"--dominant-color: #e17f7e;\" decoding=\"async\" sizes=\"(max-width: 1140px) 100vw, 1140px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/08\/fahrrad-tipps-pedalhaken-stoesst-an-reifen-diamant-blog.jpg\" alt=\"\u00dcberschneidung Pedalhaken und Vorderreifen - Diamant-Blog\" class=\"wp-image-4914 not-transparent\"\/><figcaption class=\"wp-element-caption\">Abb. 2:&nbsp;\u00dcberschneidung der&nbsp;Pedalhaken. &#8211; Diamant-Blog<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Gefahrenstellen am Fahrrad meiden<\/h2>\n\n\n\n<p>Einige Teile deines Fahrrades k\u00f6nnen bei falscher&nbsp;Handhabung Verletzungen verursachen. Vermeide daher<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>scharfkantige Stellen: Z\u00e4hne der Kettenbl\u00e4tter und einige Pedalen k\u00f6nnen scharfkantige Stellen haben.<\/li>\n\n\n\n<li>bewegliche Teile:&nbsp;Bewegliche Teile wie Seilz\u00fcge am Fahrrad k\u00f6nnen in die Haut&nbsp;schneiden.<\/li>\n\n\n\n<li>hei\u00dfe Oberfl\u00e4chen: Fahrradbremsen und deren Komponenten werden w\u00e4hrend des Fahrradtour hei\u00df. Beim E-Bike k\u00f6nnen Antrieb und Akku sehr hei\u00dft werden, wenn eine St\u00f6rung vorliegt.<\/li>\n\n\n\n<li class=\"mb-5\">Quetschstellen:&nbsp;An Klemmst\u00fccken und schwenkbaren&nbsp;Teilen, wie Bremshebel oder dort, wo die Kette&nbsp;auf das Kettenblatt l\u00e4uft, k\u00f6nntest du dich versehentlich einklemmen.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Probleme mit Fahrradrahmen oder Fahrradgabel<\/h2>\n\n\n\n<p>Tauchen w\u00e4hrend der Fahrradfahrt Probleme am Rahmen oder an der Gabel auf, kann dies zum Kontrollverlust und damit einhergehend zum Sturz f\u00fchren.&nbsp;Im Normalfall sollten auch bei hoher Geschwindigkeit kein Flattern, sondern nur harmonische&nbsp;Schwingungen oder Rahmenvibrationen zu sp\u00fcren sein.<\/p>\n\n\n\n<p class=\"mb-5\"><strong>Hinweis:<\/strong> Solltest du ein Flattern&nbsp;sp\u00fcren oder ein anderes Problem auftreten,&nbsp;verringere sofort die Geschwindigkeit&nbsp;und fahre nicht weiter. Bringe Dein Rad zum Fachh\u00e4ndler und lasse es inspizieren und reparieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Defekt am Rad durch Verschlei\u00df vermeiden &#8211; Lebensdauer der Fahrradkomponenten<\/h2>\n\n\n\n<p>Wie bei allen mechanischen Ger\u00e4ten verursacht die Nutzung auch beim Fahrrad Belastungen und Verschlei\u00df. Dies \u00e4u\u00dfert sich bei den verschiedenen Werkstoffen und Komponenten auf unterschiedliche Weise. Wenn ein Teil des Rads (z. B. Rahmen, Gabel und Komponenten) \u00fcber seine Lebensdauer hinaus verwendet wird, kann dieses Teil pl\u00f6tzlich brechen und dazu f\u00fchren, dass du die Kontrolle verlierst. Achte daher auf Risse, Kratzer oder Farb\u00e4nderungen jeglicher Form in den stark belasteten Bereichen. Diese weisen darauf hin, dass die Lebensdauer der Komponente erreicht ist und als Konsequenz ersetzt werden muss. <a title=\"\" href=\"https:\/\/www.diamantrad.com\/blog\/e-bike-akku-faq\/lebensdauer\/\" target=\"\" rel=\"noopener\">Hier gehts zur Lebensdauer des E-Bike-Akkus<\/a>.<\/p>\n\n\n\n<p>Die sichere Lebensdauer eines&nbsp;Fahrradteils wird durch folgende Gegebenheiten und Faktoren bestimmt:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Konstruktion<\/li>\n\n\n\n<li>Material<\/li>\n\n\n\n<li>Verwendung<\/li>\n\n\n\n<li>Wartung<\/li>\n\n\n\n<li>Fahrergewicht<\/li>\n\n\n\n<li>Geschwindigkeit<\/li>\n\n\n\n<li>Untergrund<\/li>\n\n\n\n<li>Au\u00dfenbedingungen&nbsp;(Feuchtigkeit, Salzgehalt,&nbsp;Temperatur usw.)<\/li>\n<\/ul>\n\n\n\n<p>Es ist daher nicht&nbsp;m\u00f6glich vorherzusagen, wann ein Teil ersetzt&nbsp;werden muss. Wenn du nicht sicher bist, ob ein Teil ersetzt werden soll, wende dich bitte an deinen Fachh\u00e4ndler.&nbsp;In einigen F\u00e4llen haben leichtere Rahmen bzw.&nbsp;Komponenten eine l\u00e4ngere Lebensdauer&nbsp;als schwerere Ausf\u00fchrungen. Leichte&nbsp;Hochleistungsfahrr\u00e4der und deren Teile erfordern&nbsp;jedoch mehr Wartungsaufwand, h\u00e4ufigere&nbsp;Inspektionen und k\u00fcrzere Austauschintervalle.<\/p>\n\n\n\n<p>Festzuhalten ist aber: Ein harter Fahrstil, das Fahren unter schwierigen Bedingungen&nbsp;oder im Allgemeinen eine intensive Nutzung mit h\u00e4ufigen Fahrten beanspruchen das Rad \u00fcberm\u00e4\u00dfig stark. Somit m\u00fcssen in diesen F\u00e4llen Fahrrad und Komponenten h\u00e4ufiger ausgewechselt werden, als bei Radfahrern, die weniger oder zur\u00fcckhaltender&nbsp;fahren.<\/p>\n\n\n\n<p>Unf\u00e4lle k\u00f6nnen ebenso zum Defekt am Rad f\u00fchren. Wenn du zum Beispiel bei einem heftigen Sto\u00df auf ein Hindernis triffst,&nbsp;kann das Fahrrad stark beansprucht werden &#8211; auch&nbsp;wenn du nicht f\u00e4llst. Pr\u00fcfe daher nach solch einem Unfall zuerst, ob es besch\u00e4digte Stellen am Rad gibt, ob sich Dein Rad ungew\u00f6hnlich verh\u00e4lt oder du ein neues Ger\u00e4usch&nbsp;wahrnimmst. Falls ja, solltest du anhalten und das&nbsp;Problem beheben bzw. von&nbsp;deinem Fahrrad-Fachh\u00e4ndler reparieren lassen. \u00dcberpr\u00fcfe das Fahrrad immer gr\u00fcndlich, bevor du wieder damit f\u00e4hrst.<\/p>\n\n\n\n<div class=\"wp-block-group mb-5\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-2\">\n\t\t\t\n\n<figure class=\"wp-block-image size-large\"><img data-dominant-color=\"6f807c\" data-has-transparency=\"false\" style=\"--dominant-color: #6f807c;\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"739\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/image-1024x739.avif\" alt=\"Image\" class=\"wp-image-53788 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/image-1024x739.avif 1024w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/image-300x217.avif 300w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/image-768x554.avif 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/image-png.avif 1140w\" \/><\/figure>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-10\">\n\t\t\t\n\n<p>Verschlissene&nbsp;Fahrradteile m\u00fcssen nicht das Ende deiner Radfahrer-Fahrrad-Beziehung bedeuten. Einzelteile k\u00f6nnen auch einfach ausgetauscht werden. Wie? Unsere bilderreiche Anleitung im Diamantrad-Blog erkl\u00e4rt dir, wie du zum Beispiel ein&nbsp;<a href=\"https:\/\/www.diamantrad.com\/blog\/fahrrad-restaurieren\/\">Diamant-Rennrad restaurieren<\/a>&nbsp;kannst.<\/p>\n\n\t<\/div>\n\n<\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Vorsicht beim Fahren mit Aerolenkern<\/h2>\n\n\n\n<p>Aerolenker sind Fahrradlenker, auf denen sich der Fahrer mit den Unterarmen anstatt mit den H\u00e4nden abst\u00fctzt. Die Radkontrolle ist hierbei niedriger als bei herk\u00f6mmlichen Fahrradlenkern. Denn wenn&nbsp;die Unterarme oder Ellenbogen beim&nbsp;Fahren auf einem Aerolenker platziert sind,&nbsp;l\u00e4sst sich das Fahrrad nicht so einfach und&nbsp;agil lenken oder anhalten.<\/p>\n\n\n\n<p class=\"mb-5\">F\u00fcr mehr Kontrolle beim Lenken&nbsp;oder Bremsen ist eine andere Haltung notwendig, sodass die H\u00e4nde in der N\u00e4he der&nbsp;Bremshebel sind und du dich nicht auf den Ellenbogen oder den Unterarmen aufst\u00fctzt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hinweise f\u00fcr Fahrradteile aus Carbonfaser<\/h2>\n\n\n\n<p class=\"bodytext\">Fahrradteile aus Carbon sind besonders leicht und deshalb ein beliebtes Material in der Fahrradbranche. Zudem hat die Carbonfaser (Kohlenstofffaser) eine h\u00f6here Festigkeit als&nbsp;Stahl oder Aluminium. Aber Vorsicht: Fahrradteile aus Carbon k\u00f6nnen trotzdem durch einen Schlag, Unfall oder&nbsp;falsche Handhabung \u00fcberlastet und somit besch\u00e4digt&nbsp;oder gebrochen werden &#8211; es verh\u00e4lt sich nur anders!<\/p>\n\n\n\n<p class=\"bodytext\">Metallteile verbiegen oder verformen&nbsp;bei \u00dcberlastung, bevor sie brechen, sodass die&nbsp;\u00dcberlastung sichtbar ist (Abb.&nbsp;8). \u00dcberlastete&nbsp;Fahrradteile aus Kohlenstofffasern verbiegen oder verformen sich&nbsp;nicht. Ein besch\u00e4digtes Carbonfaserteil kann also unver\u00e4ndert&nbsp;aussehen, aber aufgrund der Besch\u00e4digung eine viel geringere Festigkeit haben. Ist eine Belastung zu stark&nbsp;f\u00fcr die Festigkeitsgrenze der Carbonfaser, bricht sie (Abb. 8), ohne sich im Vorfeld zu verformen.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-4915\"><img data-dominant-color=\"e17f7e\" data-has-transparency=\"false\" style=\"--dominant-color: #e17f7e;\" decoding=\"async\" sizes=\"(max-width: 1140px) 100vw, 1140px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/08\/gebrochene-verbogene-fahrradgabeln-diamant-blog.jpg\" alt=\"Verschlei\u00dfte Fahrradgabeln - Diamant-Blog\" class=\"wp-image-4915 not-transparent\"\/><figcaption class=\"wp-element-caption\">Abb. 8 &#8211; Je nach Material zeigt sich der Verschlei\u00df der Fahrradteile auf unterschiedliche Weise. W\u00e4hrend sich Metallgabeln bei \u00dcberlastung verbiegen (links), brechen Carbonfaser-Gabeln (rechts), auch wenn sie insgesamt h\u00f6heren&nbsp;Belastungen standhalten. &#8211; Diamant-Blog<\/figcaption><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>Bei Fahrr\u00e4dern mit Carbon-Rahmen oder -Gabel ist somit in den folgenden F\u00e4llen besondere Vorsicht geboten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bei Unf\u00e4llen: Wenn die Carbonfaser bei einem Unfall&nbsp;oder einem Schlag nicht bricht, k\u00f6nnen&nbsp;im Materialinneren dennoch unsichtbare&nbsp;Sch\u00e4den vorhanden sein.<\/li>\n\n\n\n<li>Bei mechanischen Arbeiten: durch unsachgem\u00e4\u00df&nbsp;durchgef\u00fchrte mechanische Arbeiten k\u00f6nnen die Carbonfasern versehentlich besch\u00e4digt werden.<\/li>\n<\/ul>\n\n\n\n<p class=\"mb-5\">Die verdeckten Sch\u00e4den k\u00f6nnen dazu f\u00fchren, dass das Fahrradteil pl\u00f6tzlich w\u00e4hrend der Fahrt bricht. \u00dcberpr\u00fcfe das Fahrrad daher nach einer solchen Situation ganz genau und ersetzte Teile vorsichtshalber, wenn du dir unsicher bist. Gehe bei der Pr\u00fcfung der Carbonfaserteile wie folgt vor:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1) Fahrradteil reinigen und Oberfl\u00e4chen pr\u00fcfen<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Reinige das Fahrradteil vollst\u00e4ndig mit einem&nbsp;feuchten Tuch.<\/li>\n\n\n\n<li>Kontrolliere das Fahrrad sorgf\u00e4ltig hinsichtlich folgender Auff\u00e4lligkeiten:<\/li>\n<\/ol>\n\n\n\n<p>\u2b62 Kratzer oder Kerben<br>\u2b62 Verf\u00e4rbungen<br>\u2b62 Risse<br>\u2b62 lose Fasern<br>\u2b62 andere Oberfl\u00e4chenm\u00e4ngel<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2) Biegetest: Auf Ver\u00e4nderungen in der Steifigkeit pr\u00fcfen<\/h3>\n\n\n\n<p>Unternehme keine Fahrt, aber&nbsp;beanspruche das Fahrradteil in gewohnter Weise. Eine andere Person sollte das entsprechende Fahrradteil w\u00e4hrenddessen auf&nbsp;ungew\u00f6hnliche Bewegungen oder Ger\u00e4usche&nbsp;\u00fcberpr\u00fcfen.<\/p>\n\n\n\n<p><strong>Beispiel:<\/strong> Setze dich auf den&nbsp;Sattel, w\u00e4hrend eine andere Person darauf&nbsp;achtet, ob sich die Sattelst\u00fctze ungew\u00f6hnlich&nbsp;biegt. \u00dcberm\u00e4\u00dfiges durchbiegen w\u00e4re ein&nbsp;Hinweis auf ein m\u00f6gliches Problem.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3) Klopftest: Auf Delamination pr\u00fcfen<\/h3>\n\n\n\n<p>Vergleiche die Klopft\u00f6ne des vermutlich defekten und intakten Fahrradteils. Klingen die T\u00f6ne anders als an unbesch\u00e4digten Stellen oder an einem \u00e4hnlichen anderen Fahrradteil? Ungew\u00f6hnlich hohle oder stumpfe T\u00f6ne sind&nbsp;ein Hinweis auf ein m\u00f6gliches Problem.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Reinige das Fahrradteil vollst\u00e4ndig mit einem&nbsp;feuchten Tuch.<\/li>\n\n\n\n<li>Klopfe mit einer M\u00fcnze neben die&nbsp;vermutete Schadstelle.<\/li>\n\n\n\n<li>Achte sorgf\u00e4ltig auf Tonabweichungen.<\/li>\n<\/ol>\n\n\n\n<p class=\"mb-5\">\u00dcbrigens: Auch die Reifen bzw. R\u00e4der k\u00f6nnen aus Carbon bestehen. In unserem Beitrag <a href=\"https:\/\/www.diamantrad.com\/blog\/fahrrad-laufrad-einbauen\/\">Laufrad beim Fahrrad einbauen &amp; \u00fcberpr\u00fcfen<\/a> gehen wir auch auf dieses Szenario ein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Besondere Herausforderungen beim Fahrradfahren im Winter<\/h2>\n\n\n\n<p>Die Witterungsbedingungen in der kalten Jahreszeit erfordern eine besondere Vorsicht in der Fahrweise sowie Austattung des Fahrrad und des Radfahrers selbst. Beispielsweise solltest du auf Glatteis und in Kurven m\u00f6glichst gar nicht bremsen, sondern besser das Fahrrad ohne zu lenken ausrollen lassen.<\/p>\n\n\n\n<p>Gesetzliche Strukturen verpflichten zwar St\u00e4dte und Gemeinden dazu, stark frequentierte Stra\u00dfen zu r\u00e4umen und zu streuen. Dennoch setzen die winterlichen Bedingungen den einzelnen Fahrradteilen wie der Fahrradkette zu&nbsp; \u2013 dabei ganz besonders Streusalz. Bei E-Bikes und Pedelecs ben\u00f6tigt der Akku im Winter ganz besondere Aufmerksamkeit (siehe zu diesem Thema auch unser <a href=\"https:\/\/www.diamantrad.com\/blog\/e-bike-akku-faq\/\">E-Bike-Akku-FAQ<\/a>).<\/p>\n\n\n\n<p>Neben der Fahrradpflege darf der Radfahrer selbst nat\u00fcrlich nicht zu kurz kommen.&nbsp;So m\u00fcssen Radfahrer im Herbst und Winter aufgrund der schlechteren Lichtverh\u00e4ltnisse stets gut sichtbar sein. Je nach K\u00e4lteempfindlichkeit und der L\u00e4nge der Fahrradfahrt, ben\u00f6tigen Radler im Winter eine spezielle Fahrradausr\u00fcstung, um nicht auszuk\u00fchlen oder krank zu werden.<\/p>\n\n\n\n<p class=\"mb-5\">Alle Tipps und Hinweise rund um die Themen Winter-Radeln und <a href=\"https:\/\/www.diamantrad.com\/blog\/fahrrad-winterfest-machen\/\">Fahrrad winterfest machen<\/a>&nbsp;erh\u00e4ltst du nat\u00fcrlich auch im Diamant-Blog.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Checkliste f\u00fcr Fahrradfahrer: Vor jeder Fahrt<\/h2>\n\n\n\n<p>Fahrradfahrer sollten ihr Rad vor&nbsp;jeder Fahrt sorgf\u00e4ltig pr\u00fcfen und erst&nbsp;dann fahren, wenn alle Probleme behoben sind. Die folgende Checkliste zeigt Tipps, wie du das Fahrrad startklar machen kannst und welche Fahrradteile deine besondere Aufmerksamkeit erfordern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2713 Lenker und Vorbau kontrollieren<\/h3>\n\n\n\n<p>Lenker und Vorbau dienen zur Steuerung des Fahrrads und sind somit eines der wichtigsten Teile. Vor der Fahrt mit dem Fahrrad sollten daher folgende Punkte kontrolliert werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ist der Vorbau richtig am Vorderrad&nbsp;ausgerichtet und fest eingestellt?&nbsp;Klemme das Vorderrad zwischen die Knie und versuche den Lenker seitw\u00e4rts&nbsp;zu bewegen (Abb.&nbsp;3).<\/li>\n\n\n\n<li>Ist der Vorbau ordnungsgem\u00e4\u00df mit der Gabel&nbsp;und dem Lenker verbunden? Versuche den Lenker im Vorbau zu drehen. Der Lenker darf sich nicht&nbsp;bewegen und nicht locker sein.<\/li>\n\n\n\n<li>Werden beim Drehen des Lenkers keine Seilz\u00fcge herausgezogen oder eingeklemmt?<\/li>\n\n\n\n<li>Sind die Lenkergriffe fest?<\/li>\n\n\n\n<li>Sind die Lenkerenden abgedeckt und die Lenkerstopfen richtig in den Lenkerenden&nbsp;versenkt?&nbsp;Das offene Ende eines Lenkers k\u00f6nnte bei&nbsp;einem Sturz Schnittwunden verursachen.<\/li>\n<\/ul>\n\n\n\n<p>F\u00fcr einen gr\u00f6\u00dftm\u00f6glichen Komfort sowie optimale Bedingungen f\u00fcr eine sportliche Einheit auf dem Rad, solltest du zudem den <a href=\"https:\/\/www.diamantrad.com\/blog\/fahrradlenker-einstellen\/\">Fahrradlenker richtig einstellen<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-4917\"><img data-dominant-color=\"d47f7e\" data-has-transparency=\"false\" style=\"--dominant-color: #d47f7e;\" decoding=\"async\" sizes=\"(max-width: 1140px) 100vw, 1140px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/funktionstest-lenker-vorderrad-diamant-blog.jpg\" alt=\"Fahrradlenker am Vorderreifen ausrichten - Diamant-Blog\" class=\"wp-image-4917 not-transparent\"\/><figcaption class=\"wp-element-caption\">Abb. 3:&nbsp;Der Fahrradlenker&nbsp;sollte richtig am Vorderreifen ausgerichtet sein. &#8211; Diamant-Blog<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u2713 Laufr\u00e4der pr\u00fcfen<\/h3>\n\n\n\n<p>An den Laufr\u00e4dern sollten die folgenden Punkte vor&nbsp;jeder Fahrt mit Fahrrad \u00fcberpr\u00fcft werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ist der Reifendruck in Ordnung? Ein zu hoher Luftdruck&nbsp;kann den Reifen auf der Felge platzen&nbsp;lassen. Verwende eine&nbsp;Handpumpe mit zuverl\u00e4ssiger Druckanzeige&nbsp;und pumpe nicht zu viel Luft in&nbsp;den Reifen. Pumpe die&nbsp;Reifen ggf. entsprechend den Druckangaben an&nbsp;der Seitenwand auf.<\/li>\n\n\n\n<li>Sind die Laufr\u00e4der gerade? Drehe das Laufrad und beobachte&nbsp;die Felge, wenn sie an den Bremsbel\u00e4gen&nbsp;oder am Rahmen vorbeil\u00e4uft. Die Felge darf&nbsp;keinen H\u00f6hen- oder Seitenschlag aufweisen.<\/li>\n\n\n\n<li>Sind die Laufr\u00e4der korrekt&nbsp;befestigt? Eine falsch vorgespannte&nbsp;und geschlossene Radbefestigung kann&nbsp;dazu f\u00fchren, dass sich das Laufrad lockert&nbsp;oder unerwartet l\u00f6st. Dies kannst du pr\u00fcfen, indem du das Rad anhebst und im oberen Bereich fest auf&nbsp;den Reifen schl\u00e4gst (Abb.&nbsp;4). Das Laufrad darf nicht&nbsp;abfallen, locker sein oder sich seitw\u00e4rts&nbsp;bewegen.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-4918\"><img data-dominant-color=\"d87f7e\" data-has-transparency=\"false\" style=\"--dominant-color: #d87f7e;\" decoding=\"async\" sizes=\"(max-width: 1140px) 100vw, 1140px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/fahrrad-tipps-laufraeder-pruefen-diamant-blog.jpg\" alt=\"Festen Sitz der Laufr\u00e4der pr\u00fcfen - Diamant-Blog\" class=\"wp-image-4918 not-transparent\"\/><figcaption class=\"wp-element-caption\">Abb. 4:&nbsp;Vor der Fahrt mit dem Fahrrad sollten die Laufr\u00e4der auf einen festen Sitz \u00fcberpr\u00fcft werden. Diamant-Blog<\/figcaption><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>Es gibt verschiedene Systeme zur Befestigung&nbsp;der Laufr\u00e4der am Rahmen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Achsmuttern&nbsp;mit Gewinde<\/li>\n\n\n\n<li>Schnellspanner mit Hebel&nbsp;(Abb.&nbsp;5)<\/li>\n\n\n\n<li>Steckachsen<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-4919\"><img data-dominant-color=\"d97f7e\" data-has-transparency=\"false\" style=\"--dominant-color: #d97f7e;\" decoding=\"async\" sizes=\"(max-width: 1140px) 100vw, 1140px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/fahrrad-tipps-laufr\u00e4der-schnellspanner-diamant-blog.jpg\" alt=\"Schnellspanner an den\u00a0Laufr\u00e4dern - Diamant-Blog\" class=\"wp-image-4919 not-transparent\"\/><figcaption class=\"wp-element-caption\">Abb. 5 &#8211; Laufr\u00e4der k\u00f6nnen mit Schnellspanner am Rahmen befestigt sein:&nbsp;Vorspannmutter (1); Hebel (2). Diamant-Blog<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u2713 Bremsen testen<\/h3>\n\n\n\n<p>Ein besch\u00e4digtes oder&nbsp;falsch eingestelltes Bremssystem kann zum Kontrollverlust f\u00fchren.&nbsp;Unterziehe die Bremsen daher vor jeder Fahrt&nbsp;einer umfassenden Inspektion. Es gibt vier verschiedene Bremstypen mit unterschiedlichen Inspektionsanweisungen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Handfelgenbremsen<\/li>\n\n\n\n<li>Scheibenbremsen<\/li>\n\n\n\n<li>Nabenbremsen<\/li>\n\n\n\n<li>R\u00fccktrittbremsen<\/li>\n<\/ul>\n\n\n\n<p class=\"mb-5\"><strong>Hinweis:<\/strong> Fahre nicht mit einem Fahrrad, bei dem die Bremsen&nbsp;nicht richtig funktionieren. Bringe es zum Kundendienst deines Fachh\u00e4ndlers oder&nbsp;informiere dich bei uns, wie du die&nbsp;<a href=\"https:\/\/www.diamantrad.com\/blog\/fahrradbremsen-einstellen\/\">Fahrradbremsen pr\u00fcfen und einstellen<\/a> kannst.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Handfelgenbremsen<\/h4>\n\n\n\n<p>Handfelgenbremsen sind mit dem Handhebel durch einen Seilzug verbunden.&nbsp;Bei Bet\u00e4tigung des Hebels \u00fcben die&nbsp;Bremsbel\u00e4ge Druck auf die Felge aus.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u00e4sst sich die Handfelgenbremse frei bewegen und sich das Fahrrad entsprechend problemlos zum Halten bringen? Ziehen Sie den Hebel an: Wenn sich der Hebel bis an&nbsp;den Fahrradlenker ziehen l\u00e4sst, ist die Bremse zu locker&nbsp;eingestellt.<\/li>\n\n\n\n<li>Sind die Bremsbel\u00e4ge an der&nbsp;Felgenflanke ausgerichtet (Abb.&nbsp;6)?<\/li>\n\n\n\n<li>Betr\u00e4gt der Abstand&nbsp;zwischen Bremsbelag und Felge&nbsp;im unbet\u00e4tigten Zustand 1 bis 2&nbsp;mm? Wenn die Bremsbel\u00e4ge zu nah an der&nbsp;Felge sitzen, ist die Handfelgenbremse zu straff eingestellt.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-4920\"><img data-dominant-color=\"e47f7e\" data-has-transparency=\"false\" style=\"--dominant-color: #e47f7e;\" decoding=\"async\" sizes=\"(max-width: 1140px) 100vw, 1140px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/fahrrad-tipps-ausrichtung-der-bremsbelaege-diamant-blog.jpg\" alt=\"Ausrichtung der Bremsbel\u00e4ge bei der Handfelgenbremse - Diamant-Blog\" class=\"wp-image-4920 not-transparent\"\/><figcaption class=\"wp-element-caption\">Abb. 6 &#8211; Handfelgenbremse: Bremsbelag auf Felgenflanke ausgerichtet (1); Bremsbelag und Felge parallel mit Abstand von 1\u20132&nbsp;mm (2); Laufrichtung der Felge (3); Winkel zur Felge 0.5\u20131.0&nbsp;mm (4). &#8211; Diamant-Blog<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Scheibenbremsen<\/h4>\n\n\n\n<p>Scheibenbremsen sind mit dem Handhebel durch einen Seilzug oder&nbsp;Hydraulikschlauch verbunden. Bei Bet\u00e4tigung&nbsp;des Hebels \u00fcbt die Bremse Druck auf eine&nbsp;Scheibe aus, die an der Nabe befestigt ist.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u00e4sst sich die Scheibenbremse frei bewegen und&nbsp;sich der Fahrradreifen dadurch anhalten? Ziehen Sie f\u00fcr den Check den Hebel an: Wenn sich dieser bis an&nbsp;den Fahrradlenker ziehen l\u00e4sst, ist die Bremse zu locker&nbsp;eingestellt.<\/li>\n\n\n\n<li>Betr\u00e4gt der Abstand&nbsp;zwischen Bremsbelag und Bremsscheibe im unbet\u00e4tigten Zustand 0.25 bis 0.75&nbsp;mm? Wenn die Bremsbel\u00e4ge zu nah an der&nbsp;Scheibe sitzen, ist die Scheibenbremse nicht richtig&nbsp;ausgerichtet oder zu straff eingestellt.<\/li>\n<\/ul>\n\n\n\n<p class=\"mb-5\"><strong>Achtung<\/strong>:&nbsp;Scheibenbremsen und Scheiben werden bei Verwendung sehr hei\u00df&nbsp;und k\u00f6nnen Verbrennungen verursachen.&nbsp;Dar\u00fcber hinaus k\u00f6nnen die Scheibenkanten&nbsp;scharf sein und Schnittverletzungen&nbsp;verursachen. Ber\u00fchre die Scheibe&nbsp;oder die Scheibenbremse nicht, wenn diese hei\u00df&nbsp;sind oder die Scheibe sich dreht.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Nabenbremsen<\/h4>\n\n\n\n<p>Bei Nabenbremsen verbindet ein Seilzug den&nbsp;Bremshebel mit einer Vorrichtung in der Nabe.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wie weit muss der Bremshebel angezogen werden, um Ihr Fahrrad anzuhalten? Wenn es mehr als 15&nbsp;mm sind,&nbsp;ist die Nabenbremse zu locker eingestellt.<\/li>\n\n\n\n<li>Ab wann kommt das Rad bei Bet\u00e4tigung der Nabenbremse&nbsp; zum Stillstand?&nbsp;Wenn das Fahrrad mit weniger als 7&nbsp;mm&nbsp;Bremshebelweg zum Stillstand kommt, ist die&nbsp;Bremse zu straff eingestellt.<\/li>\n<\/ul>\n\n\n\n<p class=\"mb-5\"><strong>Achtung:<\/strong> Eine Nabenbremse wird&nbsp;bei Verwendung sehr hei\u00df und kann&nbsp;Verbrennungen verursachen. Ber\u00fchren Sie&nbsp;nicht die Nabe oder die K\u00fchlrippen, wenn&nbsp;diese hei\u00df sind.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">R\u00fccktrittbremsen<\/h4>\n\n\n\n<p>R\u00fccktrittbremsen werden bet\u00e4tigt,&nbsp;wenn du die Pedale nach hinten bewegst.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wie schnell stoppen die R\u00fccktrittbremsen die Reifen? Sie sollten greifen, bevor die&nbsp;Kurbelarme 60&nbsp;Grad (1\/6-Drehung) nach&nbsp;hinten zur\u00fcckgelegt haben.<\/li>\n\n\n\n<li>Kann sich die Antriebskette l\u00f6sen? Da sie zur Bet\u00e4tigung der R\u00fccktrittbremse erforderlich ist, sollte die Kette fest sitzen und ein vertikales Spiel zwischen 6 und 12&nbsp;mm haben (Abb.&nbsp;7).<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image alignnone mb-5\"><img decoding=\"async\" sizes=\"(max-width: 900px) 100vw, 900px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2018\/10\/fahrrad-tipps-kettenspannung-pruefen-diamant-blog.jpg\" alt=\"\u00dcberpr\u00fcfen der\u00a0Kettenspannung - Diamant-Blog\" class=\"wp-image-4923\"\/><figcaption class=\"wp-element-caption\">Abb. 7:&nbsp;\u00dcberpr\u00fcfen der&nbsp;Kettenspannung: Das vertikale Spiel sollte 6-12 mm betragen. &#8211; Diamant-Blog<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u2713 Sattel (Sitz) und Sattelst\u00fctze kontrollieren<\/h3>\n\n\n\n<p>Da der Fahrradsattel den Gro\u00dfteil deines Gewichts tr\u00e4gt, ist es wichtig, vor der Fahrt zu pr\u00fcfen, ob er ordnungsgem\u00e4\u00df befestigt ist. Versuche,&nbsp;den Sattel und die Sattelst\u00fctze im Rahmen zu&nbsp;drehen und die Sattelspitze nach oben und&nbsp;nach unten zu neigen. Dabei&nbsp;darf er sich&nbsp;nicht bewegen oder locker sein.<\/p>\n\n\n\n<p><strong>Hinweis:<\/strong> Eine ausf\u00fchrliche Anleitung, wie sich der <a href=\"https:\/\/www.diamantrad.com\/blog\/fahrradsattel-einstellen\/\">Fahrradsattel einstellen<\/a> l\u00e4sst, findest du im Diamant-Blog.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2713 Federung pr\u00fcfen<\/h3>\n\n\n\n<p>Passe die Federung an deine Fahrgewohnheiten an. Die Federungskomponenten sollten \u201eauf&nbsp;Block gehen\u201c, also \u00fcber den maximalen&nbsp;Federweg hinaus gestaucht werden k\u00f6nnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2713 Beleuchtung und Reflektoren sicherstellen<\/h3>\n\n\n\n<p>Ohne korrekte&nbsp;Beleuchtung und Reflektoren bist du f\u00fcr&nbsp;andere Verkehrsteilnehmer nicht klar&nbsp;sichtbar. Auch k\u00f6nntest du Schwierigkeiten haben, Dein Umfeld zu erkennen. Um eine Unfallgefahr durch schlechte Sichtverh\u00e4ltnisse zu vermeiden, solltest du nur mit Vorderlicht, R\u00fccklicht und Reflektoren fahren.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sind alle Reflektoren&nbsp;sauber und an der erforderlichen Stelle&nbsp;angebracht?<\/li>\n\n\n\n<li>Sind die Reflektoren abgedeckt oder&nbsp;von einem Gegenstand am Fahrrad&nbsp;verdeckt?<\/li>\n\n\n\n<li>Funktioniert die Beleuchtung korrekt?<\/li>\n\n\n\n<li>Sind die Akkus der Lichter aufgeladen bzw. wird der Dynamo mit&nbsp;Strom versorgt?<\/li>\n\n\n\n<li>Ist der Dynamo korrekt angebracht und kann sich nicht&nbsp;bewegen?<\/li>\n<\/ul>\n\n\n\n<p>In einigen L\u00e4ndern oder Gemeinden gibt&nbsp;es spezielle Vorschriften in Bezug auf die&nbsp;Beleuchtung, z.&nbsp;B. bei Farben und Typen.&nbsp;Erkundige dich, bevor du mit dem&nbsp;Rad verreist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2713 Rahmen und Gabel begutachten<\/h3>\n\n\n\n<p>Pr\u00fcfe den Rahmen und die Gabel&nbsp;vor jeder Fahrt auf Anzeichen von&nbsp;Materialerm\u00fcdung:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Einkerbungen<\/li>\n\n\n\n<li>Risse<\/li>\n\n\n\n<li>Kratzer<\/li>\n\n\n\n<li>Verformungen<\/li>\n\n\n\n<li>Verf\u00e4rbungen<\/li>\n\n\n\n<li>Ungew\u00f6hnliche Ger\u00e4usche<\/li>\n<\/ul>\n\n\n\n<p>Wenn Dein Fahrradrahmen oder die Gabel aus&nbsp;Carbonfaser gefertigt sind, solltest du die oben beschriebenen Reinigungshinweise beachten, sowie Biege- und Klopftests durchf\u00fchren (siehe oben: Hinweise f\u00fcr Fahrradteile aus Carbon).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2713 Akku beim Elektrorad pr\u00fcfen<\/h3>\n\n\n\n<p>Bei Elektror\u00e4dern wie E-Bikes oder Pedelecs kommen durch den Akku ein paar Komponenten hinzu, die vor der Fahrt kontrolliert werden m\u00fcssen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ist der Akku vollst\u00e4ndig aufgeladen?<\/li>\n\n\n\n<li>Ist das Akku-Schloss richtig verriegelt?<\/li>\n\n\n\n<li>Sichtpr\u00fcfung:\n<ul class=\"wp-block-list\">\n<li>Sind Besch\u00e4digungen am Akku zu sehen?<\/li>\n\n\n\n<li>Sind Besch\u00e4digungen am&nbsp;Antrieb zu sehen?<\/li>\n\n\n\n<li>Sind Kabelleitungen oder Steckverbindungen besch\u00e4digt?<\/li>\n\n\n\n<li>Sitzen Kabelleitungen und Steckverbindungen richtig?<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Wenn du fehlende oder besch\u00e4digte Teile entdeckst, verwende&nbsp;das Elektro-Fahrrad nicht, bis du es von einem Fachh\u00e4ndler reparieren lassen hast.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit: Pr\u00fcfe vor jeder Fahrt, ob das Rad betriebssicher ist<\/h2>\n\n\n\n<p>Nat\u00fcrlich wird jedes neue Fahrrad vorgeschriebenen Endkontrollen unterzogen. Bis das Rad schlie\u00dflich an den Endkunden verkauft wird, vergeht allerdings noch etwas Zeit. So muss es noch transportiert und gelagert werden.&nbsp;Das Rad k\u00f6nnte in einem unbeaufsichtigten Moment umgefallen oder einzelne Fahrradteile k\u00f6nnten ausgetauscht worden sein. Daher ist es erforderlich, dass Radfahrer sowohl vor der ersten Inbetriebnahme als&nbsp;auch vor jeder weiteren Fahrt zumindest die wichtigsten Fahrradteile gewissenhaft kontrollieren. Mit unseren Tipps und der praktischen Checkliste wei\u00dft du nun, worauf du achten musst. F\u00fcr alle weiteren Fragen empfehlen wir dir unsere \u00dcbersichtsseite <a href=\"https:\/\/www.diamantrad.com\/fahrradreparatur-fahrradwartung\/\">Fahrradreparatur &amp; Fahrradwartung mit Diamantrad<\/a>.<\/p>\n\n\n\n<p>Wir w\u00fcnsche dir eine gute Fahrt!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor der ersten&nbsp;Ausfahrt mit einem neuen oder geliehenen Fahrrad sollten sich Radfahrer mit der Bedienung vertraut machen, um Fehlbedienungen zu vermeiden. Indem du dabei das Rad gr\u00fcndlich durchcheckst, kannst du gleich beide To-Dos in einem Rutsch erledigen. Worauf Radfahrer vor der ersten Fahrt achten sollten und welche Fahrradteile beim Fahrrad-Check wichtig sind, erf\u00e4hrst du hier [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":11965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"slim_seo":{"title":"Fahrrad fahrbereit machen \u00bb Tipps & Checkliste f\u00fcr die Inbetriebnahme","description":"Mach Dein Fahrrad fahrbereit! Was Du vor der ersten + vor jeder weiteren Fahrt beachten musst, erf\u00e4hrst Du im Diamant-Blog."},"footnotes":""},"categories":[28],"tags":[],"class_list":["post-11602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bike-ratgeber"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/11602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/comments?post=11602"}],"version-history":[{"count":0,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/11602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/media\/11965"}],"wp:attachment":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/media?parent=11602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/categories?post=11602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/tags?post=11602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}