{"id":20800,"date":"2022-02-09T08:29:53","date_gmt":"2022-02-09T07:29:53","guid":{"rendered":"https:\/\/www.diamantrad.com\/?p=20800"},"modified":"2025-03-24T14:40:06","modified_gmt":"2025-03-24T13:40:06","slug":"reichweitenangst-so-weit-faehrt-dein-e-bike-wirklich","status":"publish","type":"post","link":"https:\/\/www.diamantrad.com\/de-DE\/blog\/reichweitenangst-so-weit-faehrt-dein-e-bike-wirklich\/","title":{"rendered":"Reichweitenangst? So weit f\u00e4hrt dein E-Bike wirklich"},"content":{"rendered":"\n<p class=\"has-text-align-left\"><strong><span class=\"TextRun SCXW46387450 BCX8\" lang=\"DE-CH\" xml:lang=\"DE-CH\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW46387450 BCX8\">Du bist dir unsicher<\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">, wie weit du mit deinem E-Bike <\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">tats\u00e4chlich fahren kannst<\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">? <\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">Wir <\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">haben pro <\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">E-Bike<\/span> <span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2 SCXW46387450 BCX8 DefaultHighlightTransition\">von Diamant<\/span> <span class=\"NormalTextRun SCXW46387450 BCX8\">f\u00fcnf verschiedene Szenarien<\/span> <span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2 SCXW46387450 BCX8\">berechnet <\/span><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2 SCXW46387450 BCX8\">.<\/span><span class=\"NormalTextRun SCXW46387450 BCX8\"> Diese geben dir einen besseren \u00dcberblick \u00fcber <\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">die E-Bike-Reichweite<\/span><span class=\"NormalTextRun SCXW46387450 BCX8\"> abh\u00e4ngig davon, wie und wo du dein E-Bike f\u00e4hrst<\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">. <\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">Los gehts<\/span><span class=\"NormalTextRun SCXW46387450 BCX8\">!<\/span><\/span><span class=\"EOP SCXW46387450 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">&nbsp;<\/span><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left\"><span data-contrast=\"auto\">Der digitale Reichweitenassistent von Bosch bildet die Grundlage f\u00fcr unsere Berechnungen. So k\u00f6nnen wir den Einfluss von einzelnen Faktoren simulieren. Wir achten darauf, m\u00f6glichst realistische Szenarien zu entwickeln, mit denen sich E-Biker orientieren k\u00f6nnen. &nbsp;Weil ziemlich viele Variablen im Spiel sind, vereinfachen wir das f\u00fcr dich einmal mit einer Tabelle.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">&nbsp;<\/span><\/p>\n\n\n\n<p> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSBpZD0iZGF0YXdyYXBwZXItY2hhcnQtcENtZ0wiIHN0eWxlPSJ3aWR0aDogMDsgbWluLXdpZHRoOiAxMDAlICFpbXBvcnRhbnQ7IGJvcmRlcjogbm9uZTsiIHRpdGxlPSJbIEluc2VydCB0aXRsZSBoZXJlIF0iIHNyYz0iaHR0cHM6Ly9kYXRhd3JhcHBlci5kd2Nkbi5uZXQvcENtZ0wvMS8iIGhlaWdodD0iMzY3IiBmcmFtZWJvcmRlcj0iMCIgc2Nyb2xsaW5nPSJubyIgYXJpYS1sYWJlbD0iVGFiZWxsZSI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><script type=\"text\/javascript\">!function(){\"use strict\";window.addEventListener(\"message\",(function(e){if(void 0!==e.data[\"datawrapper-height\"]){var t=document.querySelectorAll(\"iframe\");for(var a in e.data[\"datawrapper-height\"])for(var r=0;r<t.length;r++){if(t[r].contentWindow===e.source)t[r].style.height=e.data[\"datawrapper-height\"][a]+\"px\"}}}))}();\n<\/script><\/p>\n\n\n\n<p class=\"has-text-align-left\"><span data-contrast=\"auto\">Pro E-Bike-Modell schauen wir uns f\u00fcnf verschiedene Belastungsszenarien an. F\u00fcr alle Berechnungen sind wir von einer durchschnittlichen Trittfrequenz von 60 Pedalumdrehungen pro Minute, leichtem Wind und Sommerwetter ausgegangen. Das Gewicht haben wir f\u00fcr jedes Rad individuell berechnet als die Summe aus Fahrrad, einer 80kg schweren Person und 10kg Gep\u00e4ck. Die Durchschnittsgeschwindigkeit (inkl. allen Ampelstopps) haben wir variabel an unsere Erfahrungswerte f\u00fcr die unterschiedlichen Szenarien angepasst. Wer langsamer unterwegs ist, holt noch einmal mehr Reichweite raus.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">&nbsp;<\/span><\/p>\n\n\n\n<p><span data-contrast=\"auto\">Wir haben jedes Szenario einmal f\u00fcr jeden Unterst\u00fctzungsmodus berechnet, also Eco, Tour, Sport und Turbo. In der Realit\u00e4t f\u00e4hrst du aber nie <\/span>nur <span data-contrast=\"auto\">im Eco-Modus oder <\/span>nur <span data-contrast=\"auto\">mit Turbo. Der Mittelwert der vier Szenarios ergibt f\u00fcr jedes E-Bike eine<\/span><span data-contrast=\"auto\"> Reichweite, die du bei gleichm\u00e4\u00dfiger Nutzung aller Unterst\u00fctzungsmodi erreichen kannst. Bergauf nimmst du vielleicht mehr Unterst\u00fctzung oder auf l\u00e4ngeren flachen Strecken willst du einfach mal noch mehr gleiten.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">&nbsp;<\/span><\/p>\n\n\n\n<p><span data-contrast=\"auto\">Und was kommt dann dabei raus? Eine gro\u00dfe Tabelle.<\/span><\/p>\n\n\n\n<p> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSBpZD0iZGF0YXdyYXBwZXItY2hhcnQtUGJSZWQiIHN0eWxlPSJ3aWR0aDogMDsgbWluLXdpZHRoOiAxMDAlICFpbXBvcnRhbnQ7IGJvcmRlcjogbm9uZTsiIHRpdGxlPSJSZWljaHdlaXRlbiIgc3JjPSJodHRwczovL2RhdGF3cmFwcGVyLmR3Y2RuLm5ldC9QYlJlZC8yLyIgaGVpZ2h0PSI1MzkiIGZyYW1lYm9yZGVyPSIwIiBzY3JvbGxpbmc9Im5vIiBhcmlhLWxhYmVsPSJTcGxpdCBCYXJzIj48L2lmcmFtZT4=\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><script type=\"text\/javascript\">!function(){\"use strict\";window.addEventListener(\"message\",(function(e){if(void 0!==e.data[\"datawrapper-height\"]){var t=document.querySelectorAll(\"iframe\");for(var a in e.data[\"datawrapper-height\"])for(var r=0;r<t.length;r++){if(t[r].contentWindow===e.source)t[r].style.height=e.data[\"datawrapper-height\"][a]+\"px\"}}}))}();\n<\/script><\/p>\n\n\n\n<p><span data-contrast=\"auto\">Mit dem st\u00e4rksten E-Bike in unserem Programm, dem Zouma Deluxe+, kommst du unter h\u00f6chster Belastung (Gotthardpass-Szenario) leider doch nur 51 Kilometer weit. Wie gesagt: Du f\u00e4hrst da in unserer Berechnung mit 14km\/h einen Alpenpass hoch! (Und der ist nur 10km lang.) F\u00e4hrst du unter weitaus besseren Bedingungen wie z.B. &nbsp;in Berlin, dann hast du bereits eine Reichweite von bis zu 94 Kilometer. Das viele An- und Abfahren im Stadtverkehr dr\u00fcckt trotzdem auf die Reichweite. Am weitesten kommst du im M\u00fcnsterland-Szenario durch eine gr\u00fcne Landschaft, &nbsp;\u2013 allenfalls n\u00e4mlich 137 Kilometer. Das ist fast dreimal mehr als im Gotthardpass-Szenario.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">&nbsp;<\/span><\/p>\n\n\n\n<p class=\"mb-5\"><span data-contrast=\"auto\">Die meisten Deutschen wohnen in einer Region, die wie Berlin oder Chemnitz aussieht. Viele wollen Urlaub machen in einem Umfeld, das dem Bad T\u00f6lz \u00e4hnelt. Wenn du auf diese Werte schaust: Reichweitenangst ist wirklich kein Grund mehr, kein E-Bike zu fahren. Und: Es braucht nicht immer noch gr\u00f6\u00dfere, noch schwerere Akkus. Diese Philosophie erkennst du auch darin, wie wir unsere E-Bikes ausr\u00fcsten.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">&nbsp;<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">WELCHEN EINFLUSS HABEN X UND Y AUF DEINE E-BIKE-REICHWEITE?<\/h3>\n\n\n\n<p>Unsere E-Bikes sind&nbsp;ausschlie\u00dflich&nbsp;mit Lithium-Ionen Akkus von Bosch ausgestattet. Diese Akkus haben eine hohe Stromspeicherf\u00e4higkeit und verf\u00fcgen entweder \u00fcber 400, 500 oder 625 Wh. Je mehr du von deinem Akku abverlangst, desto geringer ist die Reichweite.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Wenn du also h\u00e4ufig mit hoher oder h\u00f6chster Unterst\u00fctzungsstufe unterwegs bist, wirst du 150km nicht erreichen. Auch der Gang, in dem du f\u00e4hrst, beeinflusst die Reichweite, denn eine h\u00f6here \u00dcbersetzung erfordert mehr Energie. Viele untersch\u00e4tzen das Anfahren aus dem Stand. Wenn du beispielsweise in der Stadt unterwegs bist und auf deiner Fahrt h\u00e4ufig nach einem roten Lichtsignal anfahren musst, brauchst du automatisch auch mehr Strom als auf der Fahrt von A nach B, auf der du nur eine kontinuierliche Geschwindigkeit h\u00e4ltst.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image mb-5\">\n<figure class=\"aligncenter size-full\"><img data-dominant-color=\"8d7f80\" data-has-transparency=\"false\" style=\"--dominant-color: #8d7f80;\" loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2022\/02\/22DIA_Life_BeryllDeluxeTIE_schwarz_300dpi_67I1150-scaled.avif\" alt=\"\" class=\"wp-image-20823 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2022\/02\/22DIA_Life_BeryllDeluxeTIE_schwarz_300dpi_67I1150-scaled.avif 2560w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2022\/02\/22DIA_Life_BeryllDeluxeTIE_schwarz_300dpi_67I1150-1024x683.avif 1024w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2022\/02\/22DIA_Life_BeryllDeluxeTIE_schwarz_300dpi_67I1150-300x200.jpg 300w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2022\/02\/22DIA_Life_BeryllDeluxeTIE_schwarz_300dpi_67I1150-768x512.jpg 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2022\/02\/22DIA_Life_BeryllDeluxeTIE_schwarz_300dpi_67I1150-1536x1024.jpg 1536w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2022\/02\/22DIA_Life_BeryllDeluxeTIE_schwarz_300dpi_67I1150-2048x1365.jpg 2048w\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">K\u00d6NNEN STEIGUNGEN ODER GEGENWIND DIE E-BIKE-REICHWEITE BEEINFLUSSEN?<\/h3>\n\n\n\n<p>Ja, absolut. Bergfahrten mit entsprechenden Steigungen sind f\u00fcr dein E-Bike wesentlich anspruchsvoller als eine gem\u00fctliche Fahrradtour durch flaches Gel\u00e4nde oder die gem\u00e4chliche Fahrt zur Arbeit. Auch Gegenwind oder ein weicher Untergrund k\u00f6nnen deinem Akku einiges mehr abverlangen, als du denkst. Ausserdem hat auch das Gesamtgewicht einen Einfluss auf die Kilometer, die du mit deinem E-Bike fahren kannst.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Aber wie viel? Die n\u00e4chste Grafik zeigt dir genau das. Hier haben wir unser Szenario Chemnitz genommen und dann einzelne Variablen nochmal modifiziert. So siehst du, wie sich deine Reichweite \u00e4ndern w\u00fcrde, wenn du z.B. von Chemnitz ins Erzgebirge f\u00e4hrst oder Gep\u00e4ck f\u00fcr eine ganze Woche mitnimmst.&nbsp;<\/p>\n\n\n\n<p>H\u00e4ttest du gedacht, dass h\u00e4ufiges Anfahren im Stadtverkehr so viel Einfluss auf deine Reichweite hat? Gro\u00dfe Unterschiede im Gewicht auch, aber eben: gro\u00dfe(!) Unterschiede. Auch deine Haltung auf dem Rad macht dich mehr oder weniger aerodynamisch. Da beeinflusst, wie weit du kommst \u2013 fast so sehr wie deine Geschwindigkeit. Der ewige Ratschlag, deine Trittfrequenz zu optimieren\u2026 na ja. Tritt so schnell, wie du willst.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-datawrapper wp-block-embed-datawrapper mb-5\"><div class=\"wp-block-embed__wrapper\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0id3AtZW1iZWRkZWQtY29udGVudCIgc2FuZGJveD0iYWxsb3ctc2NyaXB0cyIgc2VjdXJpdHk9InJlc3RyaWN0ZWQiIHRpdGxlPSJTbyB2ZXLDpG5kZXJ0IHNpY2ggZGVpbmUgUmVpY2h3ZWl0ZSwgd2Vubi4uLiIgc3JjPSJodHRwczovL2RhdGF3cmFwcGVyLmR3Y2RuLm5ldC9GR3dTTi8zLyM\/c2VjcmV0PXJhUHhNYzBldGkiIGRhdGEtc2VjcmV0PSJyYVB4TWMwZXRpIiBzY3JvbGxpbmc9Im5vIiBmcmFtZWJvcmRlcj0iMCIgaGVpZ2h0PSIzNTEiPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">DIESE FAKTOREN MUSST DU ALSO BEACHTEN<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fahrmodus (Unterst\u00fctzungsstufe)\u00a0<\/li>\n\n\n\n<li>Tretwiderstand\u00a0<\/li>\n\n\n\n<li>Fahrten mit Steigungen\u00a0\u00a0<\/li>\n\n\n\n<li>Gegenwind<\/li>\n\n\n\n<li>Untergrund\u00a0<\/li>\n\n\n\n<li>Jahreszeit\u00a0<\/li>\n\n\n\n<li>Gesamtgewicht (Gewicht des Fahrers inkl. Fahrrad und Gep\u00e4ck)\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Diese Faktoren kannst du auch abgestimmt auf dein Fahrverhalten nochmals individuell auf unserem Reichweitenrechner f\u00fcr&nbsp;<a href=\"https:\/\/www.diamantrad.com\/bikes\/ebikes\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">E-Bikes<\/a>&nbsp;ausrechnen und weisst k\u00fcnftig, wie weit du mit deinem E-Bike kommst.&nbsp;&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-group mb-5\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">Zusammen mit Bosch bieten wir dir einen E-Bike-Reichweitenrechner an. Du kannst ganz einfach ausrechnen, mit wie viel Reichweite du planen kannst.<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a role=\"button\" class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.diamantrad.com\/bikes\/technologie\/e-bike-reichweite\/\">Direkt zum E-Bike-Reichweitenrechner<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">PLANE EINEN PUFFER EIN<\/h3>\n\n\n\n<p class=\"mb-5\">Wichtig: Obwohl du mit unserer Tabelle und dem&nbsp;E-Bike-Reichweitenrechner&nbsp;von Bosch&nbsp;eine&nbsp;konkrete&nbsp;Kilometeranzahl bekommst, solltest du auf jeder Fahrt&nbsp;immer etwas Puffer einplanen.&nbsp;Nichts \u00e4rgert dich mehr, als wenn auf den letzten&nbsp;Kilometern dein Akku ausgeht. Manchmal sind das ja gerade auch die anstrengendsten Kilometer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">WEITERF\u00dcHRENDE INFORMATIONEN<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.bosch-ebike.com\/ch\/produkte\/akkus\">E-Bike-Akkus: hohe Reichweite, geringes Gewicht, einfaches Laden \u2013 Bosch eBike Systems<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.diamantrad.com\/blog\/e-bike-akku-faq\/\">E-Bike-Akkus: FAQ | Diamantrad Fragen und Antworten 2021<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.diamantrad.com\/blog\/e-bike-akku-faq\/laden\/\">E-Bike-Akku laden<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.diamantrad.com\/blog\/das-s-pedelec-als-alternative-zum-auto-wie-schlaegt-sich-das-schnelle-e-bike-im-alltag\/\">Das S-Pedelec als Alternative zum Auto<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Du bist dir unsicher, wie weit du mit deinem E-Bike tats\u00e4chlich fahren kannst? Wir haben pro E-Bike von Diamant f\u00fcnf verschiedene Szenarien berechnet . Diese geben dir einen besseren \u00dcberblick \u00fcber die E-Bike-Reichweite abh\u00e4ngig davon, wie und wo du dein E-Bike f\u00e4hrst. Los gehts!&nbsp; Der digitale Reichweitenassistent von Bosch bildet die Grundlage f\u00fcr unsere Berechnungen. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":20864,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"slim_seo":{"title":"Wie weit f\u00e4hrt mein E-Bike? | Diamantrad-Blog","description":"Wie hoch ist die Reichweite meines E-Bikes? 5 konkrete Beispiele f\u00fcr verschiedene Diamant-R\u00e4der. Jetzt informieren!"},"footnotes":""},"categories":[118],"tags":[30,131,132,133],"class_list":["post-20800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-bike-ratgeber","tag-e-bike","tag-reichweite","tag-reichweitenassistent","tag-reichweitenrechner"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/20800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/comments?post=20800"}],"version-history":[{"count":0,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/20800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/media\/20864"}],"wp:attachment":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/media?parent=20800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/categories?post=20800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/tags?post=20800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}