{"id":28858,"date":"2023-08-16T10:17:02","date_gmt":"2023-08-16T08:17:02","guid":{"rendered":"https:\/\/www.diamantrad.com\/?p=28858"},"modified":"2025-03-24T14:40:05","modified_gmt":"2025-03-24T13:40:05","slug":"von-mannheim-nach-chiti-nepal-per-bike","status":"publish","type":"post","link":"https:\/\/www.diamantrad.com\/de-DE\/blog\/von-mannheim-nach-chiti-nepal-per-bike\/","title":{"rendered":"Von Mannheim nach Chiti, Nepal per Bike"},"content":{"rendered":"\n<p><strong>Bildung ist leider in einigen L\u00e4ndern immer noch ein Privileg und nicht f\u00fcr jeden zug\u00e4nglich, wie es bei uns in Deutschland, der Schweiz und \u00d6sterreich der Fall ist. Dieser Gedanke besch\u00e4ftigt Felix Michalski schon seit einiger Zeit. Angespornt von seiner Leidenschaft f\u00fcr das Radfahren, hat er sich ein gro\u00dfes Ziel gesetzt: Das Projekt &#8222;Golden Goal Biking&#8220; &#8211; eine Fahrradreise von Mannheim nach Chiti in Nepal mit einem besonderen, Gold-werten Ziel. Er m\u00f6chte seine Begeisterung f\u00fcrs Radfahren ausleben und gleichzeitig etwas Gutes tun: Felix setzt sich mit dieser Fahrradreise f\u00fcr eine bessere Bildung in S\u00fcdostasien ein.<\/strong><\/p>\n\n\n\n<p class=\"mb-5\">Wir unterst\u00fctzen den mutigen Fahrradabenteurer und begleiten seine Reise auch auf unserem <a title=\"\" href=\"https:\/\/www.instagram.com\/diamantrad\/\" target=\"_blank\" rel=\"noopener\" aria-label=\"Opens external link in a new tab\">Instagram-Kanal<\/a>. Startschuss f\u00fcr Felix in Mannheim ist der 19. August 2023.<\/p>\n\n\n\n<p>Hier geht es direkt zum <a href=\"https:\/\/www.diamantrad.com\/blog\/koepfchen-spricht-diamantrad-podcast-nr-10\/\" target=\"_blank\" rel=\"noopener\" title=\"\" aria-label=\"Opens external link in a new tab\">Podcast mit Felix von Golden Goal Biking<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube mb-5\"><div class=\"wp-block-embed__wrapper\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iS8OWUEZDSEVOIFNQUklDSFQuIERlciBEaWFtYW50cmFkLVBvZGNhc3QgLy8gRm9sZ2UgMTA6IExpdmUgbWl0IEZlbGl4IE1pY2hhbHNraSAoR29sZGVuIEdvYWwgQmlraW5nKSIgd2lkdGg9Ijk5MiIgaGVpZ2h0PSI1NTgiIHNyYz0iaHR0cHM6Ly93d3cueW91dHViZS1ub2Nvb2tpZS5jb20vZW1iZWQvaFVSU29aN2IyNEE\/ZmVhdHVyZT1vZW1iZWQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvdz0iYWNjZWxlcm9tZXRlcjsgYXV0b3BsYXk7IGNsaXBib2FyZC13cml0ZTsgZW5jcnlwdGVkLW1lZGlhOyBneXJvc2NvcGU7IHBpY3R1cmUtaW4tcGljdHVyZTsgd2ViLXNoYXJlIiByZWZlcnJlcnBvbGljeT0ic3RyaWN0LW9yaWdpbi13aGVuLWNyb3NzLW9yaWdpbiIgYWxsb3dmdWxsc2NyZWVuPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/www.diamantrad.com\/wp-content\/uploads\/borlabs-cookie\/1\/yt_hURSoZ7b24A_hqdefault.jpg')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>YouTube<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">DAS PROJEKT GOLDEN GOAL BIKING<\/h3>\n\n\n\n<p>Felix plant, insgesamt 15.000 Kilometer auf seinem Fahrradsattel zu verbringen. Der Weg f\u00fchrt durch insgesamt 25 L\u00e4nder und startet in Mannheim. Das Ziel ist Chiti in Nepal. Ein ganzes Jahr hat er sich f\u00fcr dieses spektakul\u00e4re Abenteuer Zeit genommen. Doch der Weg ist hier nur Mittel zum Zweck: Das Ziel dieser Radreise ist es, so viele Spenden wie m\u00f6glich zu sammeln, um die New Marigold School um zus\u00e4tzliche Klassenr\u00e4ume zu versehen. Bisher existieren nur Klassenzimmer f\u00fcr die Stufen 1-8. Felix setzt sich f\u00fcr Klassenr\u00e4ume der Klassenstufen 9-12 ein. Partner f\u00fcr den Bau der Schulr\u00e4ume ist 264.education.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-dominant-color=\"9f7a84\" data-has-transparency=\"false\" style=\"--dominant-color: #9f7a84;\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2023\/08\/20230902_Kufstein_12.avif\" alt=\"\" class=\"wp-image-31523 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2023\/08\/20230902_Kufstein_12.avif 1080w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2023\/08\/20230902_Kufstein_12-240x300.jpg 240w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2023\/08\/20230902_Kufstein_12-768x960.jpg 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2023\/08\/20230902_Kufstein_12-819x1024.jpg 819w\" \/><\/figure>\n<\/div>\n\n\n<p class=\"mb-5\">Wir freuen uns, Teil der&nbsp;<a href=\"https:\/\/www.goldengoal-biking.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Golden Goal Biking Community<\/a>&nbsp;zu sein. und unterst\u00fctzen Felix mit einem&nbsp;<a href=\"https:\/\/www.diamantrad.com\/bike\/villiger-s-bl-2022-my22-1\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Diamant Villiger<\/a>, unserem weitgereisten und bew\u00e4hrten Bike Packing-Spezialrad. Gemeinsam mit Felix haben wir ein Villiger ausgew\u00e4hlt, weil wir \u00fcberzeugt sind, dass dieses Rad ihn sicher bis ans Ziel bringen wird. Fahrradfahren ist eben mehr als nur Sport. Es ist eine Lebenseinstellung und dient etwas Gr\u00f6\u00dferem. Genau das verk\u00f6rpert Golden Goal Biking f\u00fcr uns.<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-bootstrap-blocks-row row mb-5\">\n\t\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p>&nbsp;<strong>DAS GOLDEN GOAL<\/strong><\/p>\n\n\n\n<p>Felix hat auf seiner Reise von Mannheim nach Chiti ein gro\u00dfes Ziel: Spenden f\u00fcr den Bau eines neuen Schulgeb\u00e4udes in Nepal zu sammeln. Um das Golden Goal zu erreichen, ist er auf unsere Hilfe angewiesen. Worauf wartest du noch?<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a role=\"button\" class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.goldengoal-biking.com\/spenden\/\">ERFAHRE MEHR<\/a><\/div>\n<\/div>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2023\/08\/GGB_Karte_2160x1080.jpg\" alt=\"\"\/><\/figure>\n\n\t<\/div>\n\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">DAS DIAMANT VILLIGER: TRADITIONELLER STAHLRAHMEN F\u00dcR LANGE STRECKEN<\/h3>\n\n\n\n<p>Die Wahl des Fahrrads ist entscheidend, wenn es um lange Expeditionen geht. Ein zuverl\u00e4ssiges und robustes Fahrrad, das den Herausforderungen der Reise standh\u00e4lt, kann den Unterschied zwischen einer unvergesslichen Erfahrung und einer frustrierenden Fahrt ausmachen.&nbsp;<a href=\"https:\/\/www.diamantrad.com\/bike\/villiger-s-bl-2022-my22-1\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Das Villiger<\/a>&nbsp;ist ein Fahrrad, das abenteuerliche Expeditionen mit seinen Eigenschaften unterst\u00fctzt. Die 1\u00d711-Schaltung kann bei Bedarf \u00fcberall problemlos gewartet werden und bietet f\u00fcr die anstehenden Strecken die passende \u00dcbersetzung.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><strong>Wir unterst\u00fctzen Golden Goal Biking zus\u00e4tzlich mit einer Villiger-Aktion<\/strong><\/p>\n\n\n\n<p>F\u00fcr jedes&nbsp;<a href=\"https:\/\/www.diamantrad.com\/bike\/villiger-hch\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Diamant Villiger<\/a>, das wir ab Weihnachten 2023 bis zur Ankunft von Fleix in Chiti verkaufen, spenden wir 10 EUR an das Golden Goal.<\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Robustes und langlebiges Rahmendesign:<\/h3>\n\n\n\n<p>Das Villiger nutzt einen robusten Stahlrahmen, der den Strapazen einer langen Expedition standh\u00e4lt. Mit der lebenslangen Garantie, die Diamant anbietet, verspricht dieser Rahmen nicht nur Langlebigkeit, sondern auch hervorragende Stabilit\u00e4t und Steifigkeit. Holprige Pisten oder unwegsames Gel\u00e4nde auf dem Weg nach Chiti werden mit dem Villiger gut zu meistern sein. Die Touring-Geometrie sorgt zudem f\u00fcr angenehme Laufruhe. Zusammen mit dem Brooks B17 Ledersattel ist das Rad perfekt f\u00fcr lange und schmerzfreie Touren ausgelegt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Stabile Gep\u00e4cktr\u00e4ger:<\/h3>\n\n\n\n<p>Auf dem Lowrider-Gep\u00e4cktr\u00e4ger vorne und dem Heckgep\u00e4cktr\u00e4ger finden die Expeditionsausr\u00fcstung, Proviant und Technikausr\u00fcstung f\u00fcr die Social-Media-Begleitung ihren Platz. Der niedrige Schwerpunkt der Ausr\u00fcstung sorgt w\u00e4hrend der Fahrt f\u00fcr insgesamt mehr Stabilit\u00e4t.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sicherheit an erster Stelle:<\/h3>\n\n\n\n<p>Hydraulische Scheibenbremsen erm\u00f6glichen pr\u00e4zises Bremsen. Bei steilen Abfahrten oder unvorhergesehenen Hindernissen beh\u00e4lt Felix zu jeder Zeit die volle Kontrolle \u00fcber das Fahrrad und erreicht sicher sein Ziel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sehr gute Bodenhaftung:<\/h3>\n\n\n\n<p>Der Weg nach Chiti f\u00fchrt \u00fcber verschiedene Oberfl\u00e4chen wie Asphalt, Schotter und Waldwege. Mit den hochwertigen, extra-breiten Reifen von Schwalbe wird Felix nie die Bodenhaftung verlieren.<\/p>\n\n\n\n<div class=\"wp-block-group mb-5\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>Was gibt es Sch\u00f6neres, als mit dem Rad f\u00fcr eine l\u00e4ngere Zeit unterwegs zu sein und neue Orte zu entdecken? Praktisch nichts. Das geht nicht nur uns so, sondern auch vielen anderen Abenteurern wie beispielsweise Annie oder den Jungs von Bike2Sicilia. Ihre spannenden Erfahrungsberichte findest du hier:&nbsp;<a href=\"https:\/\/www.diamantrad.com\/radreisen\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Diamant auf Reisen<\/a><\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">WEITERE INFORMATIONEN<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.goldengoal-biking.com\/spenden\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Golden Goal: Spendensammlung f\u00fcr den Bau einer Schule in Nepal<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.goldengoal-biking.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Das sind Felix und Fabian von Golden Goal Biking<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/goldengoal.biking\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Golden Goal Biking auf Instagram<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Bildung ist leider in einigen L\u00e4ndern immer noch ein Privileg und nicht f\u00fcr jeden zug\u00e4nglich, wie es bei uns in Deutschland, der Schweiz und \u00d6sterreich der Fall ist. Dieser Gedanke besch\u00e4ftigt Felix Michalski schon seit einiger Zeit. Angespornt von seiner Leidenschaft f\u00fcr das Radfahren, hat er sich ein gro\u00dfes Ziel gesetzt: Das Projekt &#8222;Golden Goal [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":31527,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"slim_seo":{"title":"Von Mannheim nach Chiti, Nepal per Bike | Diamantrad","description":"Felix Michalski f\u00e4hrt mit dem Diamant Villiger nach Nepal, um dort neue Klassenzimmer zu bauen. Erfahre mehr \u00fcber Golden Goal Biking.","facebook_image":"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2023\/08\/Blog-Golden-Goal-Biking-Vorschau.jpg"},"footnotes":""},"categories":[119],"tags":[152,212,211],"class_list":["post-28858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stories","tag-bikepacking","tag-fahrradreisen","tag-golden-goal-biking"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/28858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/comments?post=28858"}],"version-history":[{"count":0,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/28858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/media\/31527"}],"wp:attachment":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/media?parent=28858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/categories?post=28858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/tags?post=28858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}