{"id":32850,"date":"2024-05-08T12:00:46","date_gmt":"2024-05-08T10:00:46","guid":{"rendered":"https:\/\/www.diamantrad.com\/?p=32850"},"modified":"2025-07-29T16:46:15","modified_gmt":"2025-07-29T14:46:15","slug":"koepfchen-spricht-diamantrad-podcast-nr-10","status":"publish","type":"post","link":"https:\/\/www.diamantrad.com\/de-DE\/blog\/koepfchen-spricht-diamantrad-podcast-nr-10\/","title":{"rendered":"K\u00f6pfchen spricht &#8211; Diamantrad Podcast Nr. 10"},"content":{"rendered":"\n<p class=\"has-text-align-left\"><strong>Einmalige Abenteuer, die das Herz ber\u00fchren, beginnen oft mit einer mutigen Entscheidung und einem klaren Ziel vor Augen. So auch die Fahrradreise von Felix von Golden Goal Biking mit einem einzigartigen goldenen Ziel: dem Bau einer Schule in Nepal! Seine Reise ist nicht nur ein gew\u00f6hnlicher Fahrradtrip &#8211; sie ist eine Mission, die Grenzen \u00fcberwindet und Gemeinschaften zusammenbringt.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left mb-5\">Seit August 2023 ist Felix mit seinem <a href=\"https:\/\/www.diamantrad.com\/de-DE\/bike\/villiger-hch\/\" title=\"Villiger HCH\">Diamant Villiger<\/a> nun schon auf dem Weg von Mannheim nach Chiti, Nepal. Mit seiner Reise sammelt er Geld f\u00fcr sein Golden Goal. Nach Ostern war er aus privaten Gr\u00fcnden kurz daheim in Deutschland und wir trafen ihn live bei Radsport Seither. Dort erz\u00e4hlte er uns, wie seine Reise ungeplant allein weiterging, wie er dann aber nie wirklich allein war, was das Golden Goal mit einem <span class=\"yt-core-attributed-string--link-inherit-color\">Fu\u00dfball zu tun hat und wie ihn Grenzen, Tiere und Schlafpl\u00e4tze bewegt haben.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reinh\u00f6ren und reinschauen: Video-Podcast auf YouTube und Spotify<\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iS8OWUEZDSEVOIFNQUklDSFQuIERlciBEaWFtYW50cmFkLVBvZGNhc3QgLy8gRm9sZ2UgMTA6IExpdmUgbWl0IEZlbGl4IE1pY2hhbHNraSAoR29sZGVuIEdvYWwgQmlraW5nKSIgd2lkdGg9Ijk5MiIgaGVpZ2h0PSI1NTgiIHNyYz0iaHR0cHM6Ly93d3cueW91dHViZS1ub2Nvb2tpZS5jb20vZW1iZWQvaFVSU29aN2IyNEE\/ZmVhdHVyZT1vZW1iZWQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvdz0iYWNjZWxlcm9tZXRlcjsgYXV0b3BsYXk7IGNsaXBib2FyZC13cml0ZTsgZW5jcnlwdGVkLW1lZGlhOyBneXJvc2NvcGU7IHBpY3R1cmUtaW4tcGljdHVyZTsgd2ViLXNoYXJlIiByZWZlcnJlcnBvbGljeT0ic3RyaWN0LW9yaWdpbi13aGVuLWNyb3NzLW9yaWdpbiIgYWxsb3dmdWxsc2NyZWVuPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/www.diamantrad.com\/wp-content\/uploads\/borlabs-cookie\/1\/yt_hURSoZ7b24A_hqdefault.jpg')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>YouTube<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-spotify wp-block-embed-spotify wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iU3BvdGlmeSBFbWJlZDogRXBpc29kZSAxMCAtIExpdmUgbWl0IEZlbGl4IHZvbiBHb2xkZW4gR29hbCBCaWtpbmciIHN0eWxlPSJib3JkZXItcmFkaXVzOiAxMnB4IiB3aWR0aD0iNjI0IiBoZWlnaHQ9IjM1MSIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbiBhbGxvdz0iYXV0b3BsYXk7IGNsaXBib2FyZC13cml0ZTsgZW5jcnlwdGVkLW1lZGlhOyBmdWxsc2NyZWVuOyBwaWN0dXJlLWluLXBpY3R1cmUiIGxvYWRpbmc9ImxhenkiIHNyYz0iaHR0cHM6Ly9vcGVuLnNwb3RpZnkuY29tL2VtYmVkL2VwaXNvZGUvM0dYNnpqUWVqeUxsQXJNMzlWZFBRZS92aWRlbz9nbz0xJnNwX2NpZD0yZGUyN2Q3NC1hMTg5LTRlZTYtYmIxZi00NTE1ZTZjZGFlYzkmdXRtX3NvdXJjZT1vZW1iZWQmdXRtX21lZGl1bT1kZXNrdG9wIj48L2lmcmFtZT4=\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Was ist Golden Goal Biking?<\/h3>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Herzlich willkommen zur zehnten Fole von unserem Podcast \u201eK\u00f6pfchen spricht\u201c \u2013 zum ersten Mal live. Meine Stimme kennt ihr, ich bin Thomas von Diamant, die Stimme von der Person, die neben mir sitzt, kennt ihr nicht. Wenn ihr Diamant folgt, dann seid ihr ihm vielleicht aber schon begegnet. Ich komme gleich zu Felix, sage aber erst einmal Hallo zu allen, die hier vor mir sitzen, die bei uns sind, bei diesem ersten Live-Podcast, den wir veranstalten f\u00fcr Diamant bei Radsport Seither. Einem kleinen wunderbaren Fahrradgesch\u00e4ft in der S\u00fcdpfalz. Ohnehin ein wundersch\u00f6nes Gebiet, um auch mal Urlaub zu machen. Vielen Dank Erik von Radsport Seither, dass wir hier sein d\u00fcrfen. Warum wir hier sind, das werden wir sicherlich noch erkl\u00e4ren. Jetzt sage ich erstmal Hallo Felix. Sch\u00f6n, dass du da bist. Felix von Golden Goal Biking ist ja seit\u2026 wie lange eigentlich bist du jetzt unterwegs?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Acht Monate bin ich jetzt auf dem Fahrrad unterwegs.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" id=\"attachment_32868\"><img data-dominant-color=\"95817d\" data-has-transparency=\"false\" style=\"--dominant-color: #95817d;\" loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-mit-Fahrrad.avif\" alt=\"\" class=\"wp-image-32868 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-mit-Fahrrad.avif 1620w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-mit-Fahrrad-300x200.avif 300w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-mit-Fahrrad-1024x683.avif 1024w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-mit-Fahrrad-768x512.avif 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-mit-Fahrrad-1536x1024.avif 1536w\" \/><figcaption class=\"wp-element-caption\">Bilder: Felix Golden Goal Biking<\/figcaption><\/figure>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Also eigentlich gerade irgendwo im Mittleren Osten, Kaukasus in der Gegend. Und trotzdem haben wir keine Kosten und M\u00fche und Magie gescheut, um dich mal kurz nach Deutschland zu bringen. Nein, du bist aus privaten Gr\u00fcnden mal kurz hier. Felix, fangen wir mal da an, was ist Golden Goal Biking?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ja, was ist Golden Goal Biking. In einem kurzen Satz ist es eine Fahrradtour mit dem Ziel, in Nepal anzukommen und dabei Spenden f\u00fcr den Bau einer Schule zu sammeln. Jetzt, wo ich acht Monate unterwegs bin, ist es, glaube ich, ein bisschen mehr geworden, was wir jetzt vielleicht in den n\u00e4chsten Minuten noch herausfinden werden. Aber ich glaube das als ganz komprimierter Satz. Ich bin im August 2023 in meiner Heimatstadt Mannheim gestartet und aktuell steht das Fahrrad von Diamant in Armenien. Ich bin hier f\u00fcr Familie und Freunde, aber schon in einer Woche geht es wieder zur\u00fcck.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Acht Monate auf dem Fahrrad unterwegs, wie sehr fehlt dir das Fahrrad genau jetzt in dem Moment?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Nicht so sehr (lacht). Ich geniesse die Pause mal ohne Fahrrad. Das hatte ich ein paar Mal auch auf der Reise und es tut gut wieder Freunde und Familie um sich rum zu haben.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Freunde und Familie ist das Stichwort. Es war ja nie der Plan alleine unterwegs zu sein, sondern du wolltest ja auch mit Freunden unterwegs sein. Dann kam eine Verletzung dazwischen und pl\u00f6tzlich warst du alleine. Und ich erinnere mich, wir haben damals miteinander gesprochen und du hast schon gesagt, dass du dich nicht so gl\u00fccklich f\u00fchlst, damit allein zu sein und zu schauen wie es l\u00e4uft. Was ist dann passiert?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Das Ganze ist leider schon relativ fr\u00fch passiert, um M\u00fcnchen rum, also nach einer Woche. Gl\u00fccklicherweise war ich bei meiner Tante, die in der N\u00e4he wohnt, da hatte ich schon mal so ein bisschen ein Umfeld, das mich aufgefangen hat. Ich denke, ich habe ein bisschen gebraucht, mich daran zu gew\u00f6hnen in dem Moment als es klar wurde, dass mein Freund Fabi verletzungsbedingt nicht mehr mitfahren kann. Da kommen dir dann auf einmal diese ganzen Gedanken, die man vorher weggeschoben hat in den Kopf und man denkt okay, wilte Tiere, Stra\u00dfenverkehr, alles was so passieren kann auf einer Weltreise mit dem Fahrrad eben. Das war auch die ersten Wochen noch ziemlich pr\u00e4sent, aber gl\u00fccklicherweise eben in den L\u00e4ndern, die man kennt, wie \u00d6sterreich, Italien\u2026<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Wo die wilden Tiere jetzt noch nicht ganz so wild sind.<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Genau! Da war das Wildschwein das einzige, was mir so in die Quere kam. Und dann wurde ich ein paarmal ins kalte Wasser geworfen. Vor allem ab dem Moment, wo ich im Balkan war, wo ich einfach durch die Situation gezwungen war, nach Hilfe zu fragen, weil mir Wasser gefehlt hat, weil ich mich verplant habe. Und dann habe ich gemerkt, dass es auch andere liebe Menschen gibt, die einem helfen, die das beeindruckend finden, was man macht. Die dann alles, was sie haben mit einem teilen. Essen, Verpflegung, Getr\u00e4nke oder dass man auch bei den Leuten duschen und das Zelt im Garten aufschlagen kann. Das hat dann richtig geholfen, die ersten Menschen zu treffen, die einem helfen und man merkt man ist gar nicht so sehr alleine, wie man denkt. Ich war am Ende also doch immer wieder mit Freunden unterwegs.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Du hast ja auch andere Menschen getroffen, die auch mit den Rad unterwegs waren. Wie ist das passiert?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Immer sehr spontan. Der ersten Person begegnete ich noch in Kroatien, die mich dann vier Tage begleitet hat, die n\u00e4chste Person traf ich in Bosnien und es war h\u00e4ufig dadurch, dass ich eben alleine war, dass ich mich dazu entschieden habe ins Hostel zu gehen, um dort wieder ein bisschen Kontakt mit anderen Reisenden zu haben. Und da waren dann gerade in Europa sehr viele andere Reisende auf dem Fahrrad unterwegs, die sich auch Istanbul oder Athen als Ziel ausgemalt haben. Und dann hat man sich darauf vereinbart irgendwie mal so ein bis zwei Wochen zusammen zu fahren. Jetzt gegen Ende hatte ich sogar auch Besuch von einem Freund gehabt, der mich zwei Wochen begleitet hat. Davor war ich zwei Monate mit Julius unterwegs gewesen, den ich \u00fcber Bekannte, die man dann auch so in Hostels trifft, kennengelernt habe. Das hat auch zwei Monate super funktioniert. Man ist also nicht allein.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Bleibt man dann auch in Kontakt? Der Julius zum Beispiel, fahrt ihr dann noch mal an anderer Stelle gemeinsam weiter?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Vielleicht. Ich glaube nicht mehr auf dieser Reise, aber ich glaube, dass ich viele, mit denen ich ein bisschen Radstrecke gemacht habe, nicht aus den Augen verlieren werde.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Du bist also nie allein, du bist immer mit Feunden unterwegs, es sind immer andere an anderen Orten, neue Freunde. Du hast jetzt schon was zu tun, die wieder alle zu besuchen auf deiner R\u00fcckreise.<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Genau (lacht). Ich glaube, das ist so eine Krankheit, die ganz viele Reisende haben. Man sagt, oh hier sind super viele neue Freunde, die man kennenlernt. Aber wenn ich realistisch bin, werde ich die wenigsten noch einmal sehen. Aber ein paar sind schon dabei. Ich hatte auch Besuch von einigen Freunden aus der Heimat und ich glaube, auch noch mal um den Bogen zu spannen, alleine hat man nochmals ein richtig neues Gef\u00fchl daf\u00fcr bekommen, welche die wichtigsten Freunde im Leben sind und mit welchen Personen man sich wirklich umgeben m\u00f6chte in seinem Leben.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><strong>Hinweis von Diamantrad:<\/strong><\/p>\n\n\n\n<p>Alle Folgen des&nbsp;<a href=\"https:\/\/www.diamantrad.com\/koepfchen-spricht-diamant-podcast\/\">Diamantrad-Podcasts<\/a>&nbsp;\u201eK\u00f6pfchen spricht\u201c findest du auf unserer \u00dcbersichtsseite. Wir w\u00fcnschen Dir viel Spa\u00df beim H\u00f6ren!<\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">VERSCHIEDENE L\u00c4NDER, VERSCHIEDENE SPRACHEN UND VIEL GASTFREUNDSCHAFT<\/h3>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Deine Eltern sind ja auch hier und ich schaue jetzt mal dahin und bitte um ein Nicken oder ein Kopfsch\u00fctteln. Ist er denn ein Fr\u00fchaufsteher in der Zwischenzeit? Ja, h\u00f6ren wir. Wie sieht denn dein typischer Rhythmus an einem ganz normalen Tag auf deiner Reise aus.<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Der ist richtig schlecht. Ich kann gar keinen richtigen Rhythmus sagen. Man nimmt sich dann irgenwie vor zu sagen, okay, ich stehe jetzt hier um 7 Uhr auf und um 8 Uhr sitze ich auf dem Rad und fahre meine irgendwie 80 bis 90 km und dann bin ich um 16 Uhr da, kann mein Zelt im Hellen aufschlagen. Aber nichts funktioniert so, wie man sich das vorstellt. Ich glaube ich hatte mehr Tage, wo ich im Dunkeln angekommen bin und noch irgendwie \u00fcber die Autobhan nachts gebrettert bin. Das sollte meine Mama jetzt vielleicht nicht h\u00f6ren (lacht). Aber ja, auf jeden Fall waren es mehr, als mir lieb sind und meistens bin ich viel zu sp\u00e4t angekommen, hab dann auch noch gekocht und bin um 10 Uhr ins Bett und dann morgens viel zu sp\u00e4t rausgekommen. Schlechter Rhythmus, aber es funktioniert.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Was kochst du unterwegs?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;So Klassiker, also nichts Spektakul\u00e4res. Nudeln.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" id=\"attachment_32872\"><img data-dominant-color=\"c7728d\" data-has-transparency=\"false\" style=\"--dominant-color: #c7728d;\" loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Zeltplatz.avif\" alt=\"\" class=\"wp-image-32872 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Zeltplatz.avif 1620w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Zeltplatz-300x200.avif 300w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Zeltplatz-1024x683.avif 1024w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Zeltplatz-768x512.avif 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Zeltplatz-1536x1024.avif 1536w\" \/><figcaption class=\"wp-element-caption\">Bilder: Felix Golden Goal Biking<\/figcaption><\/figure>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Vorhin bevor wir live gegangen sind, haben wir uns schon unterhalten. Ihr wart unterwegs, Fabio musste dann aufh\u00f6ren und das war schon eine Herausforderung f\u00fcr dich, weil du auch pl\u00f6tzlich deutlich mehr Gep\u00e4ck dabei hattest, weil du Sachen tragen musstest, die sonst er auch getragen hat. Ich erinnere mich auch, ihr seid losgefahren und nach den ersten zwei Tagen und den ersten Anstiegen hier in Deutschland habt ihr schon gesagt, oh mein Gott, wie soll das jemals werden, wenn die gro\u00dfen Berge kommen. Was war das, was am meisten \u00dcberwindung gekostet hat zur\u00fcckzulassen an Gep\u00e4ck?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Das ist eine gute Frage. Ich glaube es war ein eher pers\u00f6nlicher Gegenstand. Was mir als erstes in den Kopf schie\u00dft. Mein Papa hatte im Keller ein kleines Fernrohr, so ein Fernglas, dass ich mit dabei hatte. Das hatte ich auch genutzt als wir Wildpferde in Bosnien gesehen haben. Aber es war eigentlich unn\u00f6tiger Ballast und dann musste ich es doch schweren Herzens zur\u00fccklassen. Ich habe es dann von der T\u00fcrkei aus nach Hause geschickt. Das habe ich dann noch ein zweimal vermisst, als ich wieder Tiere gesehen habe.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Musstest du auch Gep\u00e4ck hinterherschicken, weil sich die Jahreszeiten \u00e4ndern und du doch nicht darauf eingestellt warst oder war das von Anfang an geplant?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ja, meine Freundin hat mich in Griechenland besucht und dann haben wir so ein bisschen Switch von Schlafsack gemacht und noch so ein paar anderen Sachen.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Auch das ist nochmals so ein spannendes Stichwort. Man stellt sich ja Reisende oft vor, so allein in sich gekehrt zu sein. So an zu Hause angebunden. Wie viel Zeit kostet die Kommunikation mit der Heimat oder nimmt es in Anspruch?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Kosten ist vielleicht das falsche Wort. Ich w\u00fcrde sagen, das ist zeitintensiv. Aber auch gerade in dem Moment, wo man dann eben realisiert hat, man f\u00e4hrt alleine weiter, war das super, dass ich viel Kontakt pflegen konnte. Es war dann gar nicht so schlecht, wenn man alleine nachts im Zelt war, dann sucht man den Kontakt wahrscheinlich eher, als wenn man noch eine Runde kicken geht mit Fabi.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" id=\"attachment_32884\"><img data-dominant-color=\"a9738b\" data-has-transparency=\"false\" style=\"--dominant-color: #a9738b;\" loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Kicken-mit-Kids.avif\" alt=\"\" class=\"wp-image-32884 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Kicken-mit-Kids.avif 1620w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Kicken-mit-Kids-300x200.avif 300w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Kicken-mit-Kids-1024x683.avif 1024w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Kicken-mit-Kids-768x512.avif 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Kicken-mit-Kids-1536x1024.avif 1536w\" \/><figcaption class=\"wp-element-caption\">Bilder: Felix Golden Goal Biking<\/figcaption><\/figure>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Wie gesagt sind wir bei Radsport Seither. Bevor du auf die Reise gegangen bist, hast du ja hier auch noch einen Mechaniker Crashkurs absolviert. Da h\u00f6rt jetzt Erik sicherlich sehr sehr aufmerksam zu. Wie n\u00fctzlich war es?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ja, da klingeln die Ohren. Es war sehr n\u00fctzlich. Ich hatte vor allem mit den Speichen Probleme, die wir uns hier vorher angeschaut haben. Ich glaube, ich werde kein super Fahrradmechaniker mehr im Leben, aber f\u00fcr die provisorischen L\u00f6sungen hat das auf jeden Fall geholfen. Also das war gut, dass Erik da noch mal einen Crashkurs gegeben hat.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Wenn du anderen Leuten noch einen Rat geben k\u00f6nntest, was sind die Fahrradreparaturen, die man f\u00fcr so einen lange Route doch k\u00f6nnen m\u00fcsste?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ich glaube Platten zu sagen, ist \u00fcberfl\u00fcssig. Das sollte man schon k\u00f6nnen, wenn man ein bisschen Fahrrad f\u00e4hrt. Speichen waren jetzt mein pers\u00f6nliches Problem. Ich habe aber ganz viele getroffen, die damit kein Problem hatten. Ich musste noch ein bisschen an den Schaltr\u00f6llchen rumspielen. Aber das habe ich jetzt vorher auch nicht gelernt. Das lernt man dann nebenbei alles. Ich glaube das sind die gr\u00f6ssten Sachen, sonst hatte ich nicht so viele Probleme.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Anderes Thema. Du bewegst dich ja durch sehr viele L\u00e4nder. Wie viele Grenzen sind es bis jetzt gewesen?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ich glaube ich bin jetzt in Land Nummer 16 mit Armenien. Also ich denke 15 Grenzen werden es sein, ja.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Und das sind ja auch andere Grenzen als wir sie in Europa oft kennen, weil es mehr Kontrollen gibt. Wie f\u00fchlst du dich bei solchen Grenzen?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Das Erlebnis woanders hin wieder aufzubrechen ist super unterschiedlich, aber ich w\u00fcrde sagen, mit dem Punkt, wo ich Europa verlassen habe, war es schon ein anderes Gef\u00fchl, \u00fcber Grenzen zu fahen. Gerade die Grenze Griechenland T\u00fcrkei ist auch super, also sieht irgendwie fast monumental aus. Wirklich riesige Geb\u00e4ude und du f\u00e4hrst \u00fcber die Grenze und siehst eben \u00fcberall die T\u00fcrkeiflaggen, die schon durch ihre Farbe richtig auffallen. Aber auch andere Grenzen sind schon ein spannender Moment, wenn du weisst, okay, du f\u00e4hrst jetzt heute Nacht in den Irak oder in den Iran. Ich glaube, das braucht dann so einen Tag bis man das realisiert und dann merkt man aber, die meisten Grenzen, die ich \u00fcbertreten habe, sind mir super willk\u00fcrlich vorgekommen, weil so viel schon vermischt ist von der einen zur anderen Seite. Am Ende ist es gar nicht so ein grosser Unterschied. Klar, du merkst hier und da so ein paar Sachen, aber es ist eigentlich ein ziemlicher runder Fluss mit irgendeiner willk\u00fcrlichen Grenze dazwischen.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Ich pers\u00f6nlich finde, wenn man in andere Kulturen geht, \u00e4ndert sich oft die Auswahl der S\u00fc\u00dfigkeiten im Supermarkt, abgesehen von Snickers und Mars. Also wie viel gibt es da, wo du sagst, das ist so geil, dass ich das entdeckt habe?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;In der T\u00fcrkei habe ich ganz sch\u00f6n, weniger auf dem Fahrrad, aber da habe ich ganz sch\u00f6n viel Baklava gegessen. Das war sehr gut. Und im Iran gibt es viele M\u00e4rkte, die Datteln verkaufen, in allen m\u00f6glichen Formen und Farben. Und da gibt es auch welche, die ein bisschen trockener sind, die sind zwar nicht ganz so lecker wie die feuchten, aber die kann man sich gut als Snack in die Taschen reinstecken. Ja, die waren sehr praktisch und sehr lecker.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Was ja auch immer noch mit dem Grenzen \u00fcberschreiten einhergeht, ist oft die neue Sprache. Was uns aufgefallen ist, als wir dich verfolgt haben auf Social Media, \u00fcbrigens ganz wichtig f\u00fcr alle, die interessiert sind und ihm noch nicht auf Social Media folgen, also auf Instagram und Facebook und sogar auch auf LinkedIn,&nbsp;<a href=\"https:\/\/www.instagram.com\/goldengoal.biking\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Felix Golden Goal Biking<\/a>. Das beste Golden Goal, das Deutschland je produziert hat. Alle Fu\u00dfballfans verzeihen mir das hoffentlich. Also was uns aufgefallen ist, dass du ja oft versucht hast, hier und da die Sprache mit aufzunehmen. Von welcher Sprache ist am meisten h\u00e4ngen geblieben?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ich glaube t\u00fcrkisch, weil ich die meiste Zeit dort verbracht habe und so durch Freunde schon ein bisschen Wortschatz hatte und sie auch dasselbe Alphabet verwenden. Das hat es viel einfacher gemacht als kurdische Sprachen oder iranisch, wo ich ein bisschen was gelernt habe. Aber t\u00fcrkisch ist am meisten h\u00e4ngen geblieben.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Wo bist du eigentlich jetzt ungef\u00e4hr, auf der H\u00e4lfte der Strecke?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ja, ein bisschen mehr als die H\u00e4lfte der Strecke.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Hei\u00dft aber, fast die H\u00e4lfte der Strecke hast du noch vor dir. Als ihr losgefahren seid, also wir reden dar\u00fcber von Mannheim nach Nepal zu fahren und das ist ein sehr langer Weg und ich fahre auch Fahrrad, aber wenn ich eine Tour mache, dann plane ich mir die ganze Strecke und lade sie auf mein Handy, aber das sind vielleicht so 50 oder 100 km und bei dir sind es wie viele Kilometer?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Total rund 15 000 km.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Habt ihr das vor der Tour schon komplett durchgeplant oder machst du das eigentlich immer st\u00fcckweise?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Wir hatten mal so ein bisschen eine Route ausgearbeitet, aber fast eher, um zu schauen, auf welche L\u00e4nder wir richtig Lust haben. Und dann haben wir das gepostet. Der erste Kommentar war, durch Mianmar kommt ihr nicht durch, das k\u00f6nnt ihr vergessen! Das geht gerade nicht und das ist total beschreibend f\u00fcr viele Situationen, die ich hatte. Dass es einfach keinen Sinn macht, alles vorauszuplanen und dass man sich da bisschen darauf einlassen muss, einfach mit dem Flow zu gehen. Das hat gut geklappt und ich habe viele Entscheidungen getroffen, spontan in Regionen oder L\u00e4nder zu fahren und es hat sich immer ausgezahlt. Ich galube das wird jetzt auch die letzten vier Monate so weitergehen.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Das hei\u00dft dein geplantes Ankunftsdatum ist wann?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Irgendwann im September.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Irgendwann im September. Das ist f\u00fcr alle, die zuschauen auch sehr wichtig zu erw\u00e4hnen: Diamant unterst\u00fctzt Felix und Golden Goal Biking nat\u00fcrlich und wir haben Felix ein Weihnachtsgeschenk gemacht. F\u00fcr jedes Diamant Villiger, das Rad mit dem er unterwegs ist, dass wir zwischen Weihnachten und seiner Ankunft in Nepal verkaufen, werden wir auch einen Teil an Golden Goal Biking spenden. Nutzt eure Chance, die R\u00e4der sind begrenzt, die Unterst\u00fctzung damit auch ein bisschen. Aber wir w\u00fcrden uns freuen, sie komplett auszureizen. Felix, noch einmal zu dem Golden Goal selbst. Du kommst dann da an und was passiert dann?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Das wei\u00df ich selbst noch nicht ganz. Ich glaube, das gebe ich in die H\u00e4nde der Schulleiter. Ich stehe mit denen in Kontakt und auch mit der Organisation, die aus Deutschland kommt, die die komplette Organisation des Baus der Schule \u00fcbernimmt. Ich wei\u00df, dass die Grube jetzt schon ausgehoben ist, also es steht echt gut, was die Spenden angeht. Ihr d\u00fcrft trotzdem sehr gerne noch ein bisschen was dazu legen. Genau, aber die Grube ist ausgehoben. Jetzt kommt die Monsunzeit, da kann man leider nicht weiterbauen und wenn ich ankommen werde, ist es gerade noch so Ende der Monsunzeit. Danach wird dann der Bau weitergehen, der sich noch so \u00fcber ein paar Monate zieht. Und dann schauen wir. Vielleicht ergibt sich die M\u00f6glichkeit f\u00fcr mich, dass ich noch mal aktiv dort teilnehmen kann und noch mal nach Nepal komme. Ich denke, wenn ich da bin wird es einfach ein gemeinsames Fest mit den Kindern geben.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Sch\u00f6n, f\u00fcr ein solches Golden Goal unterwegs zu sein. Du bist jetzt lange lange auf dem Fahrrad unterwegs. Wie hat sich deine Perspektive auch aufs Reisen grunds\u00e4tzlich ver\u00e4ndert und was wird f\u00fcr dich auch irgendwann danach weiter passieren? Wie wirst du danach Riesen, brauchst du noch mal ein Fahrrad?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Vielleicht (lacht). Also doch, ich habe schon ein gutes Gef\u00fchl mit dem Fahrrad. Das ist eine Art zu reisen, die ich selbst vorher auch gar nicht kannte. Das habe ich erst jetzt gross gestartet mit der ersten Tour, aber vorher habe ich das \u00fcberhaupt nicht gemacht. Ich finde das Fahrrad hat einfach das perfekte Tempo, um L\u00e4nder oder eine Region voll kennenzulernen. Laufen dauert mir ein bisschen zu lange. Mit Autofahren, da \u00fcberbr\u00fcckst du sehr sehr viele coole Sachen auf dem Weg, dann f\u00e4hrst du vielleicht nur von Stadt zu Stadt, aber was mir eigentlich am meisten Spa\u00df gemacht hat, war das dazwischen. Da habe ich auch die besondersten Begegnungen gehabt. Deswegen glaube ich, vielleicht nicht jedes mal, da w\u00e4re meine Freundin nicht so gl\u00fccklich dr\u00fcber, aber ich glaube ich werde mich noch ein paar Mal mit dem Fahrrad aufmachen zum Reisen.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Vielleicht h\u00e4tten wir da auch ein Fahrrad f\u00fcr sie, falls sie zuschaut. Sie wird uns jetzt vielleicht verfluchen, nein (lacht). Was macht wirklich so den Unterschied aus? Du sagst das Tempo, das Elebnis, aber wie unterscheidet sich dieses Erlebnis von einem normalen Urlaub, wo du einfach f\u00fcr die Erholung hingehst?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Dass man mit Menschen in Kontakt kommt und auf einer solchen Reise bist du einfach besonders exponiert. Wenn du auf dem Fahrrad unterwegs bist, f\u00e4llst du den Leuten direkt auf, sie Grinsen dich an, also selbst die Grenzkontrollen, die mit Maschinengewehr dort stehen, lachen dich an. Und dann lernst du eben Leute kennen, in den kleinsten D\u00f6rfern irgendwo im Hinterland im Iran, die dich mit dem Fahrrad sehen und dich zu sich nach Hause einladen und du darfst mit ihnen Essen teilen oder sie teilen das Essen mit dir und du erlebst Geschichten, Geschichten mit ihnen. Ich glaube, das erlebst du auf dem Rad sehr viel mehr als mit irgendeinem anderen Fortbewegungsmittel. Daf\u00fcr ist es perfekt.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Gibt es vielleicht eine Geschichte, die du gerne mit uns teilen w\u00fcrdest?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ich habe gerade an ein paar Leute aus dem Iran gedacht, aus einem ganz ganz kleinen Dorf. Ich glaube die schauen jetzt nicht zu, aber falls doch Babakal Salam. Es war super kalt, das war noch ziemlich hoch in den Bergen und wir wollten eigentlich in so einer Ruine \u00fcbernachten, einfach um uns so ein bisschen vom Wetter zu sch\u00fctzen. Dann wurden wir dabei entdeckt und dann kamen zwei Dorfbewohner, die sich erst als Polizisten ausgegeben haben und das kam uns erstmal so ein bisschen suspekt vor, weil wir schon gemerkt haben, Polizisten sind es sicherlich nicht, haben dann aber trotzdem mit denen vereinbart, dass wir mit ihnen ins Dorf kommen.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Das war mit Julius, richtig?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Das war mit Julius, genau. Das hat sich als die beste Entscheidung herausgestellt, die wir h\u00e4tten treffen k\u00f6nnen. Wir wurden dann zum Essen eingeladen und haben dann mit ihnen vereinbart, dass wir noch einen Tag l\u00e4nger bleiben. Ich war das erste mal Reiten auf einem Pferd dort. Wir waren so im Dorf unterwegs und sie haben uns gezeigt, dass ein neuer Bahnhof gebaut wurde und sie waren wirklich stolz wie Oscar, dass sie einen Bahnhof in ihrem winzigen Dorf haben. Wir haben uns alte Ruinen angeschaut, von den ersten Siedlungen dort und so entstehen so viele Geschichten. Die klingen jetzt vielleicht banal, aber wenn du das erlebst mit den Menschen dort, zum Beispiel ein Tischtennisturnier am Abend, also das kann man gar nicht beschreiben. Das war richtig sch\u00f6n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" id=\"attachment_32876\"><img data-dominant-color=\"b47e85\" data-has-transparency=\"false\" style=\"--dominant-color: #b47e85;\" loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-bei-einer-Familie-im-Iran.avif\" alt=\"\" class=\"wp-image-32876 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-bei-einer-Familie-im-Iran.avif 1620w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-bei-einer-Familie-im-Iran-300x200.avif 300w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-bei-einer-Familie-im-Iran-1024x683.avif 1024w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-bei-einer-Familie-im-Iran-768x512.avif 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-bei-einer-Familie-im-Iran-1536x1024.avif 1536w\" \/><figcaption class=\"wp-element-caption\">Bilder: Felix Golden Goal Biking<\/figcaption><\/figure>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Ich erinnere mich auch, es gab einen Moment auf deiner Reise, da hast du sehr damit gestruggelt, Probleme gehabt, wie du deine Botschaft auch r\u00fcberbringst. Wie du mit Social Media interagierst, die Zeit, die da reinfliesst, wie es dich besch\u00e4ftigt, wie es dich auch beeinflusst, wie du das Land wahrnimmst. Kannst du da noch mal kurz ein Recap geben?<\/p>\n\n\n\n<p class=\"mb-5\"><strong>Felix:<\/strong>&nbsp;Ja, ich stecke schon ziemlich viel Arbeit rein in Social Media. Vielleicht stehe ich mir da selbst im Weg, aber ich habe schon einen gewissen Qualit\u00e4tsanspruch von dem was ich da so preisgebe. Und vielleicht habe ich in dem Moment nicht ganz wertgesch\u00e4tzt, was ich schon erreicht habe. Man vergleicht sich viel mit anderen und denkt, es k\u00f6nnte besser sein, aber eigentlich k\u00f6nnte es auch schlechter sein. Ich glaube, das habe ich danach ein bisschen realisiert und hab ein ges\u00fcnderes Verh\u00e4ltnis dazu entwickelt, was ich an Arbeit reinstecke mehr in meinen Tagesablauf einfliessen zu lassen. Letztlich brauchen wir 27 000 Euro f\u00fcr den Bau der Schule. Das ist das Ziel, warum ich das mache. Ich mache es nicht prim\u00e4r, um grosser Social Media Start zu werden. Das war das, wo ich irgendiwe so eine Art von Verantwortungsgef\u00fchl gesp\u00fcrt habe, dass ich dachte, ich muss das jetzt hier erreichen, damit diese Schule stehen kann. Wir sind jetzt mittlerweile bei 19 000 Euro. Also wir sind auf einem echt guten Weg und ich glaube, dass habe ich dann irgendwann zwischen dem Irak und dem Iran so realisiert, dass ich eigentlich alles gerade genau richtig mache und das wir das Ziel erreichen, bin ich mir ganz sicher.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00dcber Russland, China und Indien nach Nepal<\/h3>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Das freut mich sehr. Unter den L\u00e4ndern, die jetzt noch vor dir stehen, welche sind das eigentlich?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Also ich fahre eine etwas au\u00dfergew\u00f6hnliche Route, weil ich mich n\u00f6rdlich des Kaspischen Meers bewege. Das hei\u00dft, ich fahre jetzt nach Georgien und Russland und dann durch alles was mit stan endet. Dann China, Pakistan, Indien und Nepal. Ja, das ist die Route.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Was ist so aktuell das, wo du sagst, ach da freue ich mich jetzt besonders drauf oder da erwarte ich vielleicht noch mal, was v\u00f6llig anders ist als alles was ich bis jetzt gesehen habe?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ich glaube Zentralasien, also Tadschikistan, Kirgistan, Usbekistan, weil ich dar\u00fcber am wenigsten wei\u00df und ich das eigentlich auch nicht von Anfang an geplant hatte, dort zu fahren und sich das dann so ergeben hat. Und ich glaube, ich hatte bisher mit diesen spontanen Entscheidungen zu sagen, dort fahre ich hin, super gute Entscheidungen getroffen. Ich war super happy damit und ich bin mir ziemlich sicher, dass mich da auch Zentralasien nicht entt\u00e4uschen wird.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Warum hast du jetzt eigentlich diese ungew\u00f6hnliche Route gew\u00e4hlt?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Es gibt verschiedene M\u00f6glichkeiten, Iran war f\u00fcr mich klar, dass ich das erleben m\u00f6chte und von dort aus hast du entweder die M\u00f6glichkeit, \u00fcber Pakistan zu fahren, dann w\u00e4re das f\u00fcr mich ehrlich gesagt zu kurz gewesen, weil dann bin ich ja schon fast in Indien, Nepal. Turkmedistan w\u00e4re eine M\u00f6glichkeit, da ist es aber ein bisschen schwieriger ein Visum zu bekommen und auch kostenspieliger, weil du einen Guide der Regierung mitnehmen musst und du w\u00e4rst zumindest nicht alleine unterwegs. Letztlich hat sich der Gedanke f\u00fcr mich festgesetzt, dass ich kein Flugzeug nehmen m\u00f6chte, um mit dem Fahrrad von A nach B zu kommen und dann blieb eigentlich nur noch die M\u00f6glichkeit Russland. Aber ich habe auch ein ganz gutes Gef\u00fchl daf\u00fcr, wenn man ein bisschen l\u00e4nger f\u00e4hrt, kommt man mit vielen anderen Reisenden in Kontakt, die ja das klingt jetzt verr\u00fcckt, aber man ist ja kein Pionier mehr, die ganze Welt wird schon beradelt und dann triffst du auch Leute, die dir echt gute Tipps geben k\u00f6nnen, wie man wo reinkommt in welches Land und wie man sich da zu verhalten hat und so weiter.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;F\u00fcr viele Menschen denen du begegnest, scheinst du ja doch so ein bisschen Pionier zu sein. Das hast du ja vorhin schon erz\u00e4hlt, wie dann die Begeisterung dort f\u00fcr jemanden mit so einem fett bepackten Fahrrad entsteht. Wie viel Fahrradkultur gibt es dort, wo du unterwegs gewesen bist?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Leider viel zu wenig. Das hat st\u00e4ndig abgenommen. Vielleicht sind die einen oder anderen, die heute zuschauen auch mal auf so Euroradwegen unterwegs gewesen, das ist in Europa echt noch alles ganz gut m\u00f6glich, aber ab der T\u00fcrkei sp\u00e4testens, f\u00e4hrst du eigentlich nur noch auf Landstra\u00dfen mit Autos zusammen. Ich glaube, als ich das geplant und die Idee hatte, hat man sich das auch ein bisschen idyllischer vorgestellt. Man f\u00e4hrt immer durch Natur und man h\u00f6rt alle drei Stunden mal ein Auto. So ist es dann leider nicht. Aber man kann sich auch hier und da mal eine Auszeit nehmen, dann fahre ich vielleicht einen Tag l\u00e4nger, aber fahre den Schotterweg, daf\u00fcr habe ich Natur. Man muss das nur so in Einklang mit dem Zeitplan bringen. Jetzt habe ich die Ursprungsfrage vergessen, kannst du die noch mal wiederholen?<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Nein, die hast du beantwortet. Natur \u00e4ndert sich, am Anfang ist alles sehr vertraut, das sieht sehr lange so aus wie du das mehr oder weniger von zu Hause kennst, dann wie du es aus dem Urlaub in Italien kennst und dann wird es irgendwann sehr anders. Du bist auch im Winter unterwegs gewesen. Wie ist der Winter anderswo?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Kacke! Das ist auf dem Fahrrad zumindest nicht so angenehm. Ich war in der T\u00fcrkei im Winter und ich glaube, wenn die T\u00fcrkei nicht so unfassbar gastfreundliche Menschen gehabt h\u00e4tte, dann w\u00e4re ich vielleicht mehr ins Zweifeln gekommen. Aber jedes Mal, wenn ich in einer Situation war, wenn ich wusste n\u00e4chste Nacht wird es -10 Grad draussen\u2026 dazu kann ich eine gute Geschichte erz\u00e4hlen. Das war irgendwo mitten in Zentralanatolien und ich wusste es wird -10 Grad in der Nacht und ich hatte eine solche Nacht schon, das kannst du mal machen, aber so zwei N\u00e4chte am St\u00fcck, das machst du nicht. Deshalb bin ich in eine Moschee gefahren und habe dort gefragt, ob es m\u00f6glich w\u00e4re, dort zu \u00fcbernachten. Dann war gerade das letzte Gebet fertig und ich hatte das mit Google Translator gezeigt und ein Mann hatte die Nachricht gesehen und gesagt, ich brauche nicht in der Moschee schlafen, ich k\u00f6nne diese Nacht mit ihm mitkommen. So hatte ich einen warmen Schlafplatz im Wohnzimmer, hatte ein tolles Gespr\u00e4ch mit einer wirklich besonderen Familie und ich bin sogar noch in der Zeitung gelandet dort im Ort, als verr\u00fcckter deutscher Tourist, der sich verirrt hat und bei der Familie gelandet ist (lacht). So ein bisschen wie wir das aus unserer Heimt kennen, wenn man durch Kleinst\u00e4dte l\u00e4uft und dann steht da in diesem Haus \u00fcbernachtete Goethe.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Also in 100 Jahren h\u00e4lt dich jemand vielleicht f\u00fcr Goethe. Das bringt noch einen guten Punkt auf. Du hast vorhin erz\u00e4hlt, dass du noch so viele Geschichten hast, auch solche, die du noch nicht erz\u00e4hlen kannst und m\u00f6chtest, weil du noch unterwegs bist und das auch alles noch verarbeitest. Schreibst du irgendwann ein Buch?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Das klingt jetzt arrogant, wenn man ja sagt, mache ich. Dann kann man das so an Weihnachten an Freunde verteilen, das eigene Buch. Aber ich glaube irgendeine Form von Medium mit dem ich mich ein bisschen l\u00e4nger als 60 Sekunden in Videos ausdr\u00fccken kann, werde ich mir schon suchen. Es kann ein Buch sein, es kann Podcast sein, ich wei\u00df noch nicht, aber irgendeine Form werde ich mir suchen, ganz sicher.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Du hast es schon angedeutet, ich schau mal ganz kurz auf die Uhr, wir sind ungef\u00e4hrt eine halbe Stunde dabei. Ich m\u00f6chte euch zu Hause auch nicht \u00fcberstrapazieren, noch eine halbe Stunde bis zur Tagesschau.<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ach, ich bin wieder in Deutschland (lacht).<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Ja, richtig. Wo stehen wir so ungef\u00e4hr bei den Spenden?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;18 500 Euro m\u00fcssen es sein.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;18 500 Euro. Das hei\u00dft, uns fehlen noch 8 500 bis wir am Ziel sind. Wie viele Kilometer sind es noch?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;6000 km.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Okay, das ist ein sch\u00f6nes Ziel effektiv. Vielleicht musst du einfach noch 2000 km Umweg auf dich nehmen, dass wir f\u00fcr jeden Kilometer noch genau einen Euro sammeln.<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Das w\u00e4re cool, dann w\u00fcrde ich es machen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" id=\"attachment_32880\"><img data-dominant-color=\"ba7b84\" data-has-transparency=\"false\" style=\"--dominant-color: #ba7b84;\" loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-auf-dem-Fahrrad.avif\" alt=\"\" class=\"wp-image-32880 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-auf-dem-Fahrrad.avif 1620w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-auf-dem-Fahrrad-300x200.avif 300w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-auf-dem-Fahrrad-1024x683.avif 1024w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-auf-dem-Fahrrad-768x512.avif 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Goal-Biking-Felix-auf-dem-Fahrrad-1536x1024.avif 1536w\" \/><figcaption class=\"wp-element-caption\">Bilder: Felix Golden Goal Biking<\/figcaption><\/figure>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;\u00dcber Umwege haben wir schon geplaudert. Du hast gesagt, es passiert ja auch oft, wenn du unterwegs bist, dass du dann auf die Karte schaust und noch mal dahin f\u00e4hrst, um noch irgendwas mitzunehmen. Em Ende, wie viel l\u00e4nger war deine Reise, als sie eigentlich h\u00e4tte sein m\u00fcssen?<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Gar nicht. Das war genau perfekt so wie es war. Im Nachhinein denkt man oft, oh da h\u00e4tte ich gerne noch l\u00e4nger Zeit verbracht oder eben anders rum, den Ort h\u00e4tte ich gerne auch noch gesehen. Aber eigentlich war es perfekt so wie es war. Man lernt mit dem Weg, den man eingeschlagen hat, zufrieden zu sein. Es war auch immer perfekt, also ich hatte super Erlebnisse. Bei allen Entscheidungen, wo ich so vor einer Gabelung stand und mich f\u00fcr eine Seite entschieden habe, war super.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Felix, so gegen Ende\u2026 eine Frage habe ich noch. Weisst du eigentlich warum wir dich so cool finden?<\/p>\n\n\n\n<p><strong>Felix<\/strong>: Ne.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Okay, wir finden dich so cool, weil es so unglaublich toll und spannend ist mitzuverfolgen wie du eine gewisse Art und Weise, ein kleines St\u00fcckchen erwachsener wirst, wie du st\u00e4ndig aber verzweifelst und in deiner Verzweiflung nie nie nie deinen Optimismus und deine Menschenfreundlichkeit verlierst. Das ist etwas, was von Anfang an, seid wir dich begleiten und da hinten steht auch der Rest von meinem Team und nickt gerade mit den K\u00f6pfen, was uns wirklich anf\u00e4sst und manchmal uns auch daheim eine kleine Tr\u00e4ne aufs Auge gedr\u00fcckt hat. Es ist so sch\u00f6n, dass wir dieses Projekt unterst\u00fctzen d\u00fcrfen, dein Storytelling ist nicht das standard Storytelling von jedem anderen Radreisenden, von denen jeder zweite auch f\u00fcr soziale Zwecke oder sonst was unterwegs ist, es ist so erfrischend menschlich und daf\u00fcr m\u00f6chte ich die Gelegenheit nutzen und einfach Danke sagen. Hier steht ja auch ein kleines Sch\u00e4chtelchen und hier steht Fahrradlegenden drauf. Na und eigentlich geht es bei diesen Fahrradlegenden um unsere Fahrr\u00e4der. Ein kleines Quartettspiel, du erinnerst dich als Kind haben wir das alle gespielt. Du bist selbst inzwischen eine unserer Legenden und deswegen ist es so fitting, dir das als Geschenk zu geben. Ich packe es jetzt mal ein. Vielen Dank, vielleicht l\u00e4sst du es hier, weil du so schon so viel Gep\u00e4ck hast. Oder vielleicht nimmst du es mit und spielst unterwegs mit vielen Leuten, die du noch triffst.<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Ich werde morgen spielen, da treffe ich mich mit meinen Freunden, die ich jetzt noch nicht gesehen habe in den zwei Wochen, seid ich hier bin. Dann nehme ich das mit und dann ja, freuen wir uns \u00fcber eine Runde Quartett.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;An dieser Stelle nutze ich dann die Gelegenheit, euch daheim zu verabschieden mit den Menschen die hier vor Ort sind und die ich jetzt anschaue haben wir noch einen Augenblick mehr. Wir werden dieses Video auch auf YouTube hochladen und auch auf Spotify, nachdem wir jetzt von Felix wissen, dass auch Videos auf Spotify funktionieren. Wenn ihr Fragen habt, hinterlasst dort eure Kommentare oder schreibt uns an, ihr findet uns entweder \u00fcber Felix direkt auf Instagram oder \u00fcber den Social Media Auftritt und die Website von&nbsp;<a href=\"https:\/\/www.instagram.com\/diamantrad\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Diamant<\/a>.<\/p>\n\n\n\n<p><strong>Felix:<\/strong>&nbsp;Genau, also&nbsp;<a href=\"https:\/\/www.instagram.com\/goldengoal.biking\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Opens external link in a new tab\">Golden Goal Biking<\/a>. Wenn ihr Fragen habt zu meiner Reise oder ihr habt eine eigene vor und braucht noch irgendwie Rat, dann meldet euch da sehr gerne. Was ich abschlie\u00dfend noch sagen m\u00f6chte, mir geht es mit euch genau so. Ich finde nicht, dass es wie eine Partnerschaft wirkt, wo es nur ums Produkt geht, sondern ich f\u00fchle mich mega wohl mit euch als meine Unterst\u00fctzer der Radtour und deswegen wollte auch ich mich bei euch bedanken.<\/p>\n\n\n\n<p><strong>Thomas:<\/strong>&nbsp;Sehr sehr gerne! Das war die zehnte Folge vom Diamant Podcast. Die erste, die wir live veranstaltet haben. Ein ganz herzliches Dankesch\u00f6n an mein Team, dass das m\u00f6glich gemacht hat, an Erik von Radsport Seither und sein Team, die das m\u00f6glich gemacht haben und an alle, die hier sind. Bis bald!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" id=\"attachment_32903\"><img data-dominant-color=\"cc7f82\" data-has-transparency=\"false\" style=\"--dominant-color: #cc7f82;\" loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" src=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Gola-Biking-Felix-im-Schnee.avif\" alt=\"\" class=\"wp-image-32903 not-transparent\" srcset=\"https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Gola-Biking-Felix-im-Schnee.avif 1620w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Gola-Biking-Felix-im-Schnee-300x200.avif 300w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Gola-Biking-Felix-im-Schnee-1024x683.avif 1024w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Gola-Biking-Felix-im-Schnee-768x512.avif 768w, https:\/\/www.diamantrad.com\/wp-content\/uploads\/2024\/05\/Golden-Gola-Biking-Felix-im-Schnee-1536x1024.avif 1536w\" \/><figcaption class=\"wp-element-caption\">Bilder: Felix Golden Goal Biking<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Einmalige Abenteuer, die das Herz ber\u00fchren, beginnen oft mit einer mutigen Entscheidung und einem klaren Ziel vor Augen. So auch die Fahrradreise von Felix von Golden Goal Biking mit einem einzigartigen goldenen Ziel: dem Bau einer Schule in Nepal! Seine Reise ist nicht nur ein gew\u00f6hnlicher Fahrradtrip &#8211; sie ist eine Mission, die Grenzen \u00fcberwindet [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":23078,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"slim_seo":{"title":"K\u00f6pfchen spricht - Diamantrad Podcast Nr. 10 | Diamantrad","description":"In dieser Folge erz\u00e4hlt Felix von Golden Goal Biking wie seine Reise ungeplant allein weiterging, wie er dann aber nie wirklich allein war und wie ihn Grenzen, Tiere und Schlafpl\u00e4tze bewegt haben."},"footnotes":""},"categories":[860,119],"tags":[259,211,258],"class_list":["post-32850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-koepfchen-spricht","category-stories","tag-felix-michalski","tag-golden-goal-biking","tag-podcast"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/32850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/comments?post=32850"}],"version-history":[{"count":3,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/32850\/revisions"}],"predecessor-version":[{"id":65439,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/posts\/32850\/revisions\/65439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/media\/23078"}],"wp:attachment":[{"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/media?parent=32850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/categories?post=32850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diamantrad.com\/de-DE\/wp-json\/wp\/v2\/tags?post=32850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}